{"id":7609,"date":"2024-06-12T16:05:52","date_gmt":"2024-06-12T14:05:52","guid":{"rendered":"https:\/\/www.obat.fr\/blog\/?p=7609"},"modified":"2024-07-30T15:27:36","modified_gmt":"2024-07-30T13:27:36","slug":"gerer-sous-traitants-btp","status":"publish","type":"post","link":"https:\/\/www.obat.fr\/blog\/gerer-sous-traitants-btp\/","title":{"rendered":"8 pratiques \u00e0 suivre pour une gestion efficace de ses sous-traitants dans le b\u00e2timent"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">En France, <strong>la sous-traitance <\/strong>est r\u00e9gie par la loi et repose sur un contrat entre deux entreprises : le donneur d\u2019ordre et le sous-traitant. Et comme pour toute relation professionnelle, elle demande une gestion hors pair et beaucoup de communication. Alors, si vous \u00eates donneur d&rsquo;ordre, <strong>comment sous-traiter un chantier<\/strong> efficacement et en toute s\u00e9curit\u00e9 ? D\u00e9couvrez 8 bonnes pratiques pour une <strong>bien g\u00e9rer ses sous-traitants<\/strong> dans le b\u00e2timent !<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Pourquoi sous-traiter dans le BTP ?<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">L\u2019entreprise sous-traitante travaille pour le donneur d\u2019ordre et lui rend des comptes, sans rapport direct avec le client final (le ma\u00eetre d\u2019ouvrage). Le donneur d\u2019ordre fournit donc un cahier des charges d\u00e9taill\u00e9 pour le <strong>contrat de sous-traitance BTP<\/strong>, compl\u00e9t\u00e9 par un planning d\u2019ex\u00e9cution. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Une <strong>entreprise sous-traitante en b\u00e2timent<\/strong> vient ainsi souvent r\u00e9pondre \u00e0 un besoin de main-d\u2019\u0153uvre ou de comp\u00e9tences sp\u00e9cifiques qu\u2019une autre entreprise ne poss\u00e8de pas en interne. La sous-traitance permet de disposer ponctuellement de ces ressources, avec<strong> beaucoup plus de flexibilit\u00e9 <\/strong>que dans le cadre d\u2019un recrutement classique. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">        <div class=\"endPostCta col-12 cta_bloc_marketplace_2\">\r\n            <div class=\"cta-column-left\">\r\n                <img decoding=\"async\" data-src=\"https:\/\/www.obat.fr\/blog\/wp-content\/uploads\/2024\/07\/Placeholder-Desktop.png\" alt=\"\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" class=\"lazyload\" style=\"--smush-placeholder-width: 644px; --smush-placeholder-aspect-ratio: 644\/400;\" \/>\r\n\r\n            <\/div>\r\n            <div class=\"cta-column-right\">\r\n                <div class=\"cta-title\">\r\n                    <div class=\"cta-title\">Trouvez des sous-traitants pour vos chantiers.<\/div>\r\n                <\/div>\r\n\r\n                                    <div class=\"cta-description\">\r\n                        Trouvez des chantiers en sous traitance pr\u00e8s de chez vous.                    <\/div>\r\n                \r\n                                    <a role=\"button\" class=\"obat-button medium-primary-white\" href=\"https:\/\/marketplace.obat.fr\/\" target=\"_self\">\r\n                        <span>Trouver un pro<\/span>\r\n                        <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"12\" height=\"12\" viewBox=\"0 0 12 12\" fill=\"none\">\r\n                            <path d=\"M1 6L11 6M11 6L7.25 10M11 6L7.25 2\" stroke=\"currentColor\" stroke-width=\"1.5\" stroke-linecap=\"round\" stroke-linejoin=\"round\"><\/path>\r\n                        <\/svg>\r\n                    <\/a>\r\n                \r\n            <\/div>\r\n        <\/div>\r\n     <\/p>\n\n\n\n<h2 class=\"wp-block-heading\">8 conseils pour g\u00e9rer ses sous-traitants<\/h2>\n\n\n\n<h3 class=\"wp-block-heading\">1. Bien d\u00e9finir vos besoins en mati\u00e8re de sous-traitance<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Avant de faire appel \u00e0 du personnel sous-traitant, il est indispensable d\u2019\u00e9valuer pr\u00e9cis\u00e9ment vos <strong>besoins en main-d\u2019\u0153uvre <\/strong>suppl\u00e9mentaire. Il est crucial de bien planifier les ressources internes, c\u2019est-\u00e0-dire avoir une vue claire des disponibilit\u00e9s de votre propre personnel afin de mieux identifier les manques \u00e0 combler. Vous aurez \u00e9galement plus de facilit\u00e9 \u00e0 comparer les diff\u00e9rentes offres des sous-traitants en fonction de ce dont vous avez r\u00e9ellement besoin.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">2. S\u00e9lectionnez les bonnes entreprises sous-traitantes<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Le choix du partenaire est une \u00e9tape cruciale pour le succ\u00e8s de la collaboration. Prenez le temps de vous informer sur l\u2019<strong>entreprise candidate<\/strong> : a-t-elle une bonne r\u00e9putation ? Engage-t-elle un personnel qualifi\u00e9 et employ\u00e9 selon un contrat de travail r\u00e9glementaire ? Ses ouvriers sont-ils form\u00e9s aux normes de s\u00e9curit\u00e9 ? Dans le secteur du b\u00e2timent, il est particuli\u00e8rement important de faire preuve de prudence. V\u00e9rifiez ses qualifications, la conformit\u00e9 de son personnel ou encore le respect des mesures de s\u00e9curit\u00e9.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em>A lire \u00e9galement : <a href=\"https:\/\/www.obat.fr\/blog\/choisir-sous-traitant\/\" target=\"_blank\" rel=\"noreferrer noopener\">Combien choisir ses sous-traitants dans le BTP ? 8 conseils<\/a><\/em><\/p>\n\n\n\n<h3 class=\"wp-block-heading\">3. Contr\u00f4lez la conformit\u00e9 des sous-traitants<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Pour g\u00e9rer effectivement vos sous-traitants, il est \u00e9galement essentiel de vous prot\u00e9ger l\u00e9galement contre les mauvaises pratiques. Ces derniers doivent en effet exercer en conformit\u00e9 avec la<strong> Loi Sapin II <\/strong>et la loi relative au <a href=\"https:\/\/www.novethic.fr\/lexique\/detail\/devoir-de-vigilance.html\" target=\"_blank\" rel=\"noreferrer noopener\">devoir de vigilance<\/a>. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Il est donc indispensable pour l\u2019entreprise donneuse d\u2019ordre de collecter et v\u00e9rifier tous les <strong>documents administratifs des sous-traitants <\/strong>pour \u00e9viter d\u2019engager la responsabilit\u00e9 de son entreprise. N\u2019h\u00e9sitez pas aussi \u00e0 \u00e9tablir un <strong>r\u00e9f\u00e9rentiel des sous-traitant<\/strong>s bas\u00e9 sur leur conformit\u00e9 et leurs comp\u00e9tences, afin de les s\u00e9lectionner plus efficacement \u00e0 court et moyen terme.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">4. Mettez en place une charte de bonnes pratiques<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Une bonne<strong> gestion des sous-traitants<\/strong> permet de garantir la bonne ex\u00e9cution du chantier pendant les travaux. Nous vous conseillons donc d\u2019\u00e9tablir une <strong>charte partenariale<\/strong> de bonnes pratiques afin de pr\u00e9ciser :&nbsp;<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>les mesures de travail \u00e0 respecter pendant la dur\u00e9e de la prestation ;<\/li>\n\n\n\n<li>les r\u00e8gles de s\u00e9curit\u00e9 ;<\/li>\n\n\n\n<li>les conditions d&rsquo;encadrement ;<\/li>\n\n\n\n<li>l&rsquo;ad\u00e9quation du travail confi\u00e9 ;<\/li>\n\n\n\n<li>les d\u00e9lais de r\u00e9ception de chantier ;<\/li>\n\n\n\n<li>les dispositifs juridiques existants, en pr\u00e9cisant notamment les obligations du sous-traitant ;<\/li>\n\n\n\n<li>une approche d\u2019\u00e9changes globale pour un chantier r\u00e9ussi ;<\/li>\n\n\n\n<li>les difficult\u00e9s organisationnelles et de tr\u00e9sorerie \u00e0 anticiper.<\/li>\n<\/ul>\n\n\n\n<h3 class=\"wp-block-heading\">5. Encadrez la relation professionnelle par un contrat<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">L\u2019\u00e9dition d\u2019un <strong>contrat de sous-traitance<\/strong> permet de ma\u00eetriser les risques de travail dissimul\u00e9 et de se prot\u00e9ger en cas de litige. Il est ainsi possible d\u2019inclure des <strong>clauses sp\u00e9cifiques<\/strong> comme la garantie de bonne fin, les p\u00e9nalit\u00e9s pour retard de chantier, les responsabilit\u00e9s et assurances, ou encore les obligations de fournir des documents administratifs. \u00c0 savoir qu\u2019il existe des <strong>mod\u00e8les de contrat pr\u00e9d\u00e9finis<\/strong> pour r\u00e9duire le temps consacr\u00e9 \u00e0 leur r\u00e9daction et optimiser votre gestion de la sous-traitance.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em>A lire \u00e9galement : <a href=\"https:\/\/www.obat.fr\/blog\/contrat-sous-traitance-btp\/\" target=\"_blank\" rel=\"noreferrer noopener\">Mod\u00e8le de contrat de sous-traitance : quelles sont les r\u00e8gles dans le BTP ?<\/a><\/em><\/p>\n\n\n\n<h3 class=\"wp-block-heading\">6. Suivez la bonne ex\u00e9cution du chantier de sous-traitance<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">G\u00e9rer ses sous-traitants passe \u00e9videmment par un <strong>suivi de chantier <\/strong>efficace. Ceci vous permettra de contr\u00f4ler le respect des obligations contractuelles et \u00e9viter les mauvaises surprises, mais aussi de vous assurer de la qualit\u00e9 et de la conformit\u00e9 des travaux r\u00e9alis\u00e9s par les sous-traitants. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Pour cela, des <strong>inspections r\u00e9guli\u00e8res <\/strong>doivent \u00eatre effectu\u00e9es et le <strong>respect des d\u00e9lais<\/strong> v\u00e9rifi\u00e9. Un syst\u00e8me de r\u00e9compenses et de sanctions peut \u00eatre mis en place pour encourager les performances exceptionnelles ou p\u00e9naliser le non-respect des termes du contrat !<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">7. G\u00e9rer ses sous-traitants en anticipant les probl\u00e8mes <\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Une gestion des sous-traitants efficace passe par une <strong>anticipation des probl\u00e8mes et des conflits <\/strong>: cela vous permettra d\u2019\u00e9viter les litiges juridiques et les retards de chantier. La rigueur et la m\u00e9diation sont essentielles. D\u00e8s qu\u2019un probl\u00e8me survient, il faut l&rsquo;aborder rapidement et trouver des solutions. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Pour cela, appuyez-vous sur la <strong>clause de r\u00e8glement des diff\u00e9rends <\/strong>de votre contrat de sous-traitance, qui sp\u00e9cifie les moyens de r\u00e9soudre les conflits. En cas de conflit persistant, vous pouvez recourir \u00e0 une m\u00e9diation. Si celle-ci \u00e9choue, il est possible d&rsquo;envisager une action en justice.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em>A lire \u00e9galement : <a href=\"https:\/\/www.obat.fr\/blog\/assurance-sous-traitance-btp\/\" target=\"_blank\" rel=\"noreferrer noopener\">Quelles sont les assurances obligatoires en sous-traitance BTP ?<\/a><\/em><\/p>\n\n\n\n<h3 class=\"wp-block-heading\">8. Communiquez tout au long du projet<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">La sous-traitance en b\u00e2timent exige un <strong>\u00e9change d\u2019informations fluide et transparent<\/strong>. Une bonne communication est essentielle pour tout projet de construction. Elle permet de renforcer la coh\u00e9sion au sein de votre entreprise et de partager efficacement les plannings et les obligations li\u00e9s aux contrats de sous-traitance. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Adoptez des pratiques simples comme :<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>l\u2019\u00e9laboration d\u2019un rapport apr\u00e8s chaque visite de chantier et l\u2019envoi d\u2019une copie au ma\u00eetre d\u2019ouvrage ;<\/li>\n\n\n\n<li>l\u2019organisation r\u00e9guli\u00e8re des r\u00e9unions de chantier pour rencontrer tous les intervenants et discuter des progr\u00e8s ;<\/li>\n\n\n\n<li>la prise en main de vos responsabilit\u00e9s et obligations envers vos employ\u00e9s, vos sous-traitants et vos clients.<\/li>\n<\/ul>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<p class=\"wp-block-paragraph\">Vous l\u2019aurez compris : bien g\u00e9rer ses sous-traitants permet de r\u00e9duire les risques et d\u2019assurer la rentabilit\u00e9 des entreprises du BTP. Pour sous-traiter dans les meilleures conditions, n\u2019h\u00e9sitez pas \u00e0 vous munir d\u2019outils pour cr\u00e9er un contrat de sous-traitance en BTP en quelques clics, ou bien pour mettre en place et suivre votre planning de chantier sur une plateforme digitale, accessible \u00e0 tous. De nombreuses solutions existent pour vous simplifier la t\u00e2che, ainsi qu\u2019\u00e0 votre sous-traitant BTP !<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">        <div class=\"endPostCta col-12 cta_bloc_generic\">\r\n            <div class=\"cta-column-left\">\r\n                <img decoding=\"async\" data-src=\"https:\/\/www.obat.fr\/blog\/wp-content\/uploads\/2026\/06\/Export-4-1.jpg\" alt=\"\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" class=\"lazyload\" style=\"--smush-placeholder-width: 1394px; --smush-placeholder-aspect-ratio: 1394\/876;\" \/>\r\n\r\n            <\/div>\r\n            <div class=\"cta-column-right\">\r\n                <div class=\"cta-title\">\r\n                    <div class=\"cta-title\">Obat est pr\u00eat pour la facturation \u00e9lectronique !<\/div>\r\n                <\/div>\r\n\r\n                \r\n                                    <a role=\"button\" class=\"obat-button medium-primary-white\" href=\"http:\/\/www.obat.fr\/click?campaign=1550\" target=\"_blank\">\r\n                        <span>D\u00e9marrer l\u2019essai gratuit<\/span>\r\n                        <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"12\" height=\"12\" viewBox=\"0 0 12 12\" fill=\"none\">\r\n                            <path d=\"M1 6L11 6M11 6L7.25 10M11 6L7.25 2\" stroke=\"currentColor\" stroke-width=\"1.5\" stroke-linecap=\"round\" stroke-linejoin=\"round\"><\/path>\r\n                        <\/svg>\r\n                    <\/a>\r\n                \r\n            <\/div>\r\n        <\/div>\r\n    <\/p>\n\n\n<div class=\"kk-star-ratings kksr-auto kksr-align-left kksr-valign-bottom\"\n    data-payload='{&quot;align&quot;:&quot;left&quot;,&quot;id&quot;:&quot;7609&quot;,&quot;slug&quot;:&quot;default&quot;,&quot;valign&quot;:&quot;bottom&quot;,&quot;ignore&quot;:&quot;&quot;,&quot;reference&quot;:&quot;auto&quot;,&quot;class&quot;:&quot;&quot;,&quot;count&quot;:&quot;0&quot;,&quot;legendonly&quot;:&quot;&quot;,&quot;readonly&quot;:&quot;&quot;,&quot;score&quot;:&quot;0&quot;,&quot;starsonly&quot;:&quot;&quot;,&quot;best&quot;:&quot;5&quot;,&quot;gap&quot;:&quot;5&quot;,&quot;greet&quot;:&quot;Notez cet article&quot;,&quot;legend&quot;:&quot;0\\\/5 - (0 vote)&quot;,&quot;size&quot;:&quot;16&quot;,&quot;title&quot;:&quot;8 pratiques \u00e0 suivre pour une gestion efficace de ses sous-traitants dans le b\u00e2timent&quot;,&quot;width&quot;:&quot;0&quot;,&quot;_legend&quot;:&quot;{score}\\\/{best} - ({count} {votes})&quot;,&quot;font_factor&quot;:&quot;1.25&quot;}'>\n            \n<div class=\"kksr-stars\">\n    \n<div class=\"kksr-stars-inactive\">\n            <div class=\"kksr-star\" data-star=\"1\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 16px; height: 16px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" data-star=\"2\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 16px; height: 16px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" data-star=\"3\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 16px; height: 16px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" data-star=\"4\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 16px; height: 16px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" data-star=\"5\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 16px; height: 16px;\"><\/div>\n        <\/div>\n    <\/div>\n    \n<div class=\"kksr-stars-active\" style=\"width: 0px;\">\n            <div class=\"kksr-star\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 16px; height: 16px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 16px; height: 16px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 16px; height: 16px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 16px; height: 16px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 16px; height: 16px;\"><\/div>\n        <\/div>\n    <\/div>\n<\/div>\n                \n\n<div class=\"kksr-legend\" style=\"font-size: 12.8px;\">\n            <span class=\"kksr-muted\">Notez cet article<\/span>\n    <\/div>\n    <\/div>\n","protected":false},"excerpt":{"rendered":"<p>En France, la sous-traitance est r\u00e9gie par la loi et repose sur un contrat entre deux entreprises : le donneur d\u2019ordre et le sous-traitant. Et comme pour toute relation professionnelle, elle demande une gestion hors pair et beaucoup de communication. Alors, si vous \u00eates donneur d&rsquo;ordre, comment sous-traiter un chantier efficacement et en toute s\u00e9curit\u00e9 [&hellip;]<\/p>\n","protected":false},"author":11,"featured_media":7611,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[3,25],"tags":[],"class_list":["post-7609","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-gestion-entreprise","category-recrutement-management"],"acf":{"adam_posts_cta_bloc":{"adam_cb_image":7885,"adam_cb_titre":"","adam_cb_description":"","adam_cb_cta":{"title":"D\u00e9marrer l\u2019essai gratuit","url":"http:\/\/marketplace.obat.fr\/","target":"_blank"}},"hide_the_universal_cta":true},"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.6 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Comment g\u00e9rer ses sous-traitants dans le BTP ? 8 bonnes pratiques<\/title>\n<meta name=\"description\" content=\"Vous souhaitez commencer \u00e0 sous-traiter vos chantiers ? Voici nos conseils pour bien g\u00e9rer vos sous-traitants dans le BTP.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.obat.fr\/blog\/gerer-sous-traitants-btp\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"8 pratiques \u00e0 suivre pour une gestion efficace de ses sous-traitants dans le b\u00e2timent\" \/>\n<meta property=\"og:description\" content=\"Vous souhaitez commencer \u00e0 sous-traiter vos chantiers ? Voici nos conseils pour bien g\u00e9rer vos sous-traitants dans le BTP.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.obat.fr\/blog\/gerer-sous-traitants-btp\/\" \/>\n<meta property=\"og:site_name\" content=\"Blog Obat\" \/>\n<meta property=\"article:published_time\" content=\"2024-06-12T14:05:52+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-07-30T13:27:36+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.obat.fr\/blog\/wp-content\/uploads\/2024\/06\/gerer-sous-traitents-btp.png\" \/>\n\t<meta property=\"og:image:width\" content=\"735\" \/>\n\t<meta property=\"og:image:height\" content=\"360\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Mathilde Fauconnier\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Mathilde Fauconnier\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.obat.fr\\\/blog\\\/gerer-sous-traitants-btp\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.obat.fr\\\/blog\\\/gerer-sous-traitants-btp\\\/\"},\"author\":{\"name\":\"Mathilde Fauconnier\",\"@id\":\"https:\\\/\\\/www.obat.fr\\\/blog\\\/#\\\/schema\\\/person\\\/d6a74201e2ceca55da5c6e236380077e\"},\"headline\":\"8 pratiques \u00e0 suivre pour une gestion efficace de ses sous-traitants dans le b\u00e2timent\",\"datePublished\":\"2024-06-12T14:05:52+00:00\",\"dateModified\":\"2024-07-30T13:27:36+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.obat.fr\\\/blog\\\/gerer-sous-traitants-btp\\\/\"},\"wordCount\":1161,\"image\":{\"@id\":\"https:\\\/\\\/www.obat.fr\\\/blog\\\/gerer-sous-traitants-btp\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.obat.fr\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/gerer-sous-traitents-btp.png\",\"articleSection\":[\"Gestion d'entreprise\",\"Recrutement et management\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.obat.fr\\\/blog\\\/gerer-sous-traitants-btp\\\/\",\"url\":\"https:\\\/\\\/www.obat.fr\\\/blog\\\/gerer-sous-traitants-btp\\\/\",\"name\":\"Comment g\u00e9rer ses sous-traitants dans le BTP ? 8 bonnes pratiques\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.obat.fr\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.obat.fr\\\/blog\\\/gerer-sous-traitants-btp\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.obat.fr\\\/blog\\\/gerer-sous-traitants-btp\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.obat.fr\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/gerer-sous-traitents-btp.png\",\"datePublished\":\"2024-06-12T14:05:52+00:00\",\"dateModified\":\"2024-07-30T13:27:36+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.obat.fr\\\/blog\\\/#\\\/schema\\\/person\\\/d6a74201e2ceca55da5c6e236380077e\"},\"description\":\"Vous souhaitez commencer \u00e0 sous-traiter vos chantiers ? Voici nos conseils pour bien g\u00e9rer vos sous-traitants dans le BTP.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.obat.fr\\\/blog\\\/wp-json\\\/wp\\\/v2\\\/posts\\\/7609#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.obat.fr\\\/blog\\\/gerer-sous-traitants-btp\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.obat.fr\\\/blog\\\/gerer-sous-traitants-btp\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.obat.fr\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/gerer-sous-traitents-btp.png\",\"contentUrl\":\"https:\\\/\\\/www.obat.fr\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/gerer-sous-traitents-btp.png\",\"width\":735,\"height\":360,\"caption\":\"g\u00e9rer sous-traitants\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.obat.fr\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.obat.fr\\\/blog\\\/\",\"name\":\"Blog Obat\",\"description\":\"Blog Obat\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.obat.fr\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.obat.fr\\\/blog\\\/#\\\/schema\\\/person\\\/d6a74201e2ceca55da5c6e236380077e\",\"name\":\"Mathilde Fauconnier\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0a2f3a6912b4ed6e6822f1a7af825dd54683111e0146dafed3d083e913dd4b61?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0a2f3a6912b4ed6e6822f1a7af825dd54683111e0146dafed3d083e913dd4b61?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0a2f3a6912b4ed6e6822f1a7af825dd54683111e0146dafed3d083e913dd4b61?s=96&d=mm&r=g\",\"caption\":\"Mathilde Fauconnier\"},\"description\":\"R\u00e9dactrice web SEO, j\u2019accompagne Obat depuis 3 ans dans la cr\u00e9ation de contenus en d\u00e9cryptant les sp\u00e9cificit\u00e9s de la gestion du b\u00e2timent pour les artisans.\",\"sameAs\":[\"https:\\\/\\\/www.linkedin.com\\\/in\\\/mathilde-fauconnier-743180b3\\\/\"],\"url\":\"https:\\\/\\\/www.obat.fr\\\/blog\\\/author\\\/mathilde\\\/\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.obat.fr\\\/blog\\\/wp-json\\\/wp\\\/v2\\\/posts\\\/7609#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.obat.fr\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Blog\",\"item\":\"https:\\\/\\\/www.obat.fr\\\/blog\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Wp Json\",\"item\":\"https:\\\/\\\/www.obat.fr\\\/blog\\\/blog\\\/wp-json\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Wp\",\"item\":\"https:\\\/\\\/www.obat.fr\\\/blog\\\/blog\\\/wp-json\\\/wp\\\/\"},{\"@type\":\"ListItem\",\"position\":5,\"name\":\"V2\",\"item\":\"https:\\\/\\\/www.obat.fr\\\/blog\\\/blog\\\/wp-json\\\/wp\\\/v2\\\/\"},{\"@type\":\"ListItem\",\"position\":6,\"name\":\"Posts\",\"item\":\"https:\\\/\\\/www.obat.fr\\\/blog\\\/blog\\\/wp-json\\\/wp\\\/v2\\\/posts\\\/\"},{\"@type\":\"ListItem\",\"position\":7,\"name\":\"7609\",\"item\":\"https:\\\/\\\/www.obat.fr\\\/blog\\\/blog\\\/wp-json\\\/wp\\\/v2\\\/posts\\\/7609\\\/\"}]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Comment g\u00e9rer ses sous-traitants dans le BTP ? 8 bonnes pratiques","description":"Vous souhaitez commencer \u00e0 sous-traiter vos chantiers ? Voici nos conseils pour bien g\u00e9rer vos sous-traitants dans le BTP.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.obat.fr\/blog\/gerer-sous-traitants-btp\/","og_locale":"fr_FR","og_type":"article","og_title":"8 pratiques \u00e0 suivre pour une gestion efficace de ses sous-traitants dans le b\u00e2timent","og_description":"Vous souhaitez commencer \u00e0 sous-traiter vos chantiers ? Voici nos conseils pour bien g\u00e9rer vos sous-traitants dans le BTP.","og_url":"https:\/\/www.obat.fr\/blog\/gerer-sous-traitants-btp\/","og_site_name":"Blog Obat","article_published_time":"2024-06-12T14:05:52+00:00","article_modified_time":"2024-07-30T13:27:36+00:00","og_image":[{"width":735,"height":360,"url":"https:\/\/www.obat.fr\/blog\/wp-content\/uploads\/2024\/06\/gerer-sous-traitents-btp.png","type":"image\/png"}],"author":"Mathilde Fauconnier","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Mathilde Fauconnier","Dur\u00e9e de lecture estim\u00e9e":"6 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.obat.fr\/blog\/gerer-sous-traitants-btp\/#article","isPartOf":{"@id":"https:\/\/www.obat.fr\/blog\/gerer-sous-traitants-btp\/"},"author":{"name":"Mathilde Fauconnier","@id":"https:\/\/www.obat.fr\/blog\/#\/schema\/person\/d6a74201e2ceca55da5c6e236380077e"},"headline":"8 pratiques \u00e0 suivre pour une gestion efficace de ses sous-traitants dans le b\u00e2timent","datePublished":"2024-06-12T14:05:52+00:00","dateModified":"2024-07-30T13:27:36+00:00","mainEntityOfPage":{"@id":"https:\/\/www.obat.fr\/blog\/gerer-sous-traitants-btp\/"},"wordCount":1161,"image":{"@id":"https:\/\/www.obat.fr\/blog\/gerer-sous-traitants-btp\/#primaryimage"},"thumbnailUrl":"https:\/\/www.obat.fr\/blog\/wp-content\/uploads\/2024\/06\/gerer-sous-traitents-btp.png","articleSection":["Gestion d'entreprise","Recrutement et management"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/www.obat.fr\/blog\/gerer-sous-traitants-btp\/","url":"https:\/\/www.obat.fr\/blog\/gerer-sous-traitants-btp\/","name":"Comment g\u00e9rer ses sous-traitants dans le BTP ? 8 bonnes pratiques","isPartOf":{"@id":"https:\/\/www.obat.fr\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.obat.fr\/blog\/gerer-sous-traitants-btp\/#primaryimage"},"image":{"@id":"https:\/\/www.obat.fr\/blog\/gerer-sous-traitants-btp\/#primaryimage"},"thumbnailUrl":"https:\/\/www.obat.fr\/blog\/wp-content\/uploads\/2024\/06\/gerer-sous-traitents-btp.png","datePublished":"2024-06-12T14:05:52+00:00","dateModified":"2024-07-30T13:27:36+00:00","author":{"@id":"https:\/\/www.obat.fr\/blog\/#\/schema\/person\/d6a74201e2ceca55da5c6e236380077e"},"description":"Vous souhaitez commencer \u00e0 sous-traiter vos chantiers ? Voici nos conseils pour bien g\u00e9rer vos sous-traitants dans le BTP.","breadcrumb":{"@id":"https:\/\/www.obat.fr\/blog\/wp-json\/wp\/v2\/posts\/7609#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.obat.fr\/blog\/gerer-sous-traitants-btp\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.obat.fr\/blog\/gerer-sous-traitants-btp\/#primaryimage","url":"https:\/\/www.obat.fr\/blog\/wp-content\/uploads\/2024\/06\/gerer-sous-traitents-btp.png","contentUrl":"https:\/\/www.obat.fr\/blog\/wp-content\/uploads\/2024\/06\/gerer-sous-traitents-btp.png","width":735,"height":360,"caption":"g\u00e9rer sous-traitants"},{"@type":"WebSite","@id":"https:\/\/www.obat.fr\/blog\/#website","url":"https:\/\/www.obat.fr\/blog\/","name":"Blog Obat","description":"Blog Obat","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.obat.fr\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/www.obat.fr\/blog\/#\/schema\/person\/d6a74201e2ceca55da5c6e236380077e","name":"Mathilde Fauconnier","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/0a2f3a6912b4ed6e6822f1a7af825dd54683111e0146dafed3d083e913dd4b61?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/0a2f3a6912b4ed6e6822f1a7af825dd54683111e0146dafed3d083e913dd4b61?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/0a2f3a6912b4ed6e6822f1a7af825dd54683111e0146dafed3d083e913dd4b61?s=96&d=mm&r=g","caption":"Mathilde Fauconnier"},"description":"R\u00e9dactrice web SEO, j\u2019accompagne Obat depuis 3 ans dans la cr\u00e9ation de contenus en d\u00e9cryptant les sp\u00e9cificit\u00e9s de la gestion du b\u00e2timent pour les artisans.","sameAs":["https:\/\/www.linkedin.com\/in\/mathilde-fauconnier-743180b3\/"],"url":"https:\/\/www.obat.fr\/blog\/author\/mathilde\/"},{"@type":"BreadcrumbList","@id":"https:\/\/www.obat.fr\/blog\/wp-json\/wp\/v2\/posts\/7609#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.obat.fr\/blog\/"},{"@type":"ListItem","position":2,"name":"Blog","item":"https:\/\/www.obat.fr\/blog\/blog\/"},{"@type":"ListItem","position":3,"name":"Wp Json","item":"https:\/\/www.obat.fr\/blog\/blog\/wp-json\/"},{"@type":"ListItem","position":4,"name":"Wp","item":"https:\/\/www.obat.fr\/blog\/blog\/wp-json\/wp\/"},{"@type":"ListItem","position":5,"name":"V2","item":"https:\/\/www.obat.fr\/blog\/blog\/wp-json\/wp\/v2\/"},{"@type":"ListItem","position":6,"name":"Posts","item":"https:\/\/www.obat.fr\/blog\/blog\/wp-json\/wp\/v2\/posts\/"},{"@type":"ListItem","position":7,"name":"7609","item":"https:\/\/www.obat.fr\/blog\/blog\/wp-json\/wp\/v2\/posts\/7609\/"}]}]}},"_links":{"self":[{"href":"https:\/\/www.obat.fr\/blog\/wp-json\/wp\/v2\/posts\/7609","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.obat.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.obat.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.obat.fr\/blog\/wp-json\/wp\/v2\/users\/11"}],"replies":[{"embeddable":true,"href":"https:\/\/www.obat.fr\/blog\/wp-json\/wp\/v2\/comments?post=7609"}],"version-history":[{"count":0,"href":"https:\/\/www.obat.fr\/blog\/wp-json\/wp\/v2\/posts\/7609\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.obat.fr\/blog\/wp-json\/wp\/v2\/media\/7611"}],"wp:attachment":[{"href":"https:\/\/www.obat.fr\/blog\/wp-json\/wp\/v2\/media?parent=7609"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.obat.fr\/blog\/wp-json\/wp\/v2\/categories?post=7609"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.obat.fr\/blog\/wp-json\/wp\/v2\/tags?post=7609"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}