{"id":6642,"date":"2023-12-04T18:20:10","date_gmt":"2023-12-04T17:20:10","guid":{"rendered":"https:\/\/www.obat.fr\/blog\/?p=6642"},"modified":"2024-01-10T15:04:50","modified_gmt":"2024-01-10T14:04:50","slug":"rachat-de-societe","status":"publish","type":"post","link":"https:\/\/www.obat.fr\/blog\/rachat-de-societe\/","title":{"rendered":"Rachat de soci\u00e9t\u00e9 : tout ce qu&rsquo;il faut savoir en 2026"},"content":{"rendered":"\n<p>Le<strong> rachat de soci\u00e9t\u00e9<\/strong> est tr\u00e8s int\u00e9ressant pour les personnes qui d\u00e9sirent se lancer dans l\u2019entrepreneuriat sans partir de z\u00e9ro. Vous pouvez ainsi acqu\u00e9rir une entreprise qui fonctionne d\u00e9j\u00e0, et notamment qui a fait ses preuves en termes de chiffres d\u2019affaires et de rentabilit\u00e9. <strong>Comment racheter une entreprise<\/strong> ? Quels sont les avantages et inconv\u00e9nients de la reprise d\u2019entreprise ? O\u00f9 trouver une<strong> annonce de cession<\/strong> d\u2019entreprise ? Nous r\u00e9pondons \u00e0 toutes vos questions dans ce guide complet !<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Rachat de soci\u00e9t\u00e9 : en quoi \u00e7a consiste ?<\/h2>\n\n\n\n<p>Comme son nom l\u2019indique, le <strong>rachat d\u2019entreprise<\/strong> consiste \u00e0 acqu\u00e9rir une entreprise existante. L&rsquo;acqu\u00e9reur peut opter pour l&rsquo;achat de tout ou partie des actifs du c\u00e9dant. La <strong>reprise d&rsquo;entreprise<\/strong> peut se d\u00e9rouler de diff\u00e9rentes fa\u00e7ons, en fonction de la structure de l&rsquo;entreprise concern\u00e9e. <\/p>\n\n\n\n<p>Le repreneur potentiel a le choix entre :<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>racheter le fonds de commerce, ou acqu\u00e9rir les titres des actionnaires ou associ\u00e9s dans le cas d&rsquo;une soci\u00e9t\u00e9 ;<\/li>\n\n\n\n<li>se limiter au rachat du fonds de commerce pour une entreprise individuelle.<\/li>\n<\/ul>\n\n\n\n<p>Et contrairement \u00e0 certaines id\u00e9es re\u00e7ues, cette op\u00e9ration ne se limite pas au<strong> rachat d\u2019entreprise en difficult\u00e9<\/strong> : de nombreux dirigeants cherchent \u00e0 vendre des structures qui fonctionnent tr\u00e8s bien pour se consacrer \u00e0 d\u2019autres projets par exemple !<\/p>\n\n\n\n<p><em>A lire \u00e9galement : <a href=\"https:\/\/www.obat.fr\/blog\/devenir-travailleur-independant\/\" target=\"_blank\" rel=\"noreferrer noopener\">Devenir travailleur ind\u00e9pendant : le guide complet<\/a><\/em><\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Quel est l&rsquo;int\u00e9r\u00eat de racheter une soci\u00e9t\u00e9 ?<\/h2>\n\n\n\n<h3 class=\"wp-block-heading\">Acc\u00e9der \u00e0 une base client\u00e8le d\u00e9j\u00e0 \u00e9tablie<\/h3>\n\n\n\n<p>Poss\u00e9der une client\u00e8le loyale est crucial dans l&rsquo;entrepreneuriat pour la croissance et la p\u00e9rennit\u00e9 d&rsquo;une entreprise. Cette composante essentielle du<strong> fonds de commerce<\/strong> garantit des revenus constants pour l&rsquo;entreprise. Alors que la cr\u00e9ation d&rsquo;une entreprise implique la prospection de nouveaux clients, le <strong>rachat de soci\u00e9t\u00e9<\/strong> existante offre l&rsquo;avantage d&rsquo;une client\u00e8le d\u00e9j\u00e0 \u00e9tablie !<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Profiter d\u2019un r\u00e9seau de partenaires<\/h3>\n\n\n\n<p>Lors de la fondation d&rsquo;une entreprise, il est n\u00e9cessaire d&rsquo;\u00e9tablir des relations avec des banques, fournisseurs et autres prestataires. Souvent, se forger une r\u00e9putation parmi ces acteurs cl\u00e9s demande des ann\u00e9es apr\u00e8s la cr\u00e9ation de son activit\u00e9 professionnelle ! Par cons\u00e9quent, la<strong> reprise d\u2019une entreprise<\/strong> bien \u00e9tablie (en physique ou en digital) signifie h\u00e9riter de relations d\u00e9j\u00e0 solides.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">D\u00e9buter avec une infrastructure pr\u00eate \u00e0 l\u2019emploi<\/h3>\n\n\n\n<p>Fonder une entreprise exige de recruter du personnel qualifi\u00e9 et de trouver des locaux, ce qui peut \u00eatre difficile lorsqu\u2019on manque de temps ou d\u2019exp\u00e9rience. En revanche, <strong>racheter une entreprise existante<\/strong> permet d&rsquo;\u00e9conomiser un temps pr\u00e9cieux en termes de recrutement et d&rsquo;organisation de la structure ! Vous avez d\u00e9j\u00e0 les locaux et vous pouvez r\u00e9embaucher le personnel actuel si c\u2019est pertinent.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Les risques de la reprise d\u2019entreprise<\/h2>\n\n\n\n<h3 class=\"wp-block-heading\">Supporter le co\u00fbt du rachat de la soci\u00e9t\u00e9<\/h3>\n\n\n\n<p><strong>Racheter une soci\u00e9t\u00e9<\/strong> peut s&rsquo;av\u00e9rer on\u00e9reux, donc il est essentiel de s&rsquo;assurer de sa rentabilit\u00e9 avant de s&rsquo;engager. Cela n\u00e9cessite une analyse approfondie pour \u00e9valuer les actions et la valeur de l&rsquo;entreprise. \u00c0 savoir que bien que le co\u00fbt initial de la reprise puisse \u00eatre \u00e9lev\u00e9, l&rsquo;investissement peut \u00eatre amorti rapidement si l&rsquo;entreprise est prosp\u00e8re !<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Faire ses preuves imm\u00e9diatement<\/h3>\n\n\n\n<p>Un nouveau dirigeant qui reprend une entreprise est souvent compar\u00e9 \u00e0 son pr\u00e9d\u00e9cesseur. Clients, employ\u00e9s et fournisseurs peuvent \u00e9valuer les diff\u00e9rences dans la gestion commerciale ou le management entre l&rsquo;ancien et le nouveau dirigeant. Apr\u00e8s un<strong> rachat de soci\u00e9t\u00e9<\/strong>, le nouveau dirigeant doit faire ses preuves imm\u00e9diatement. Il a peu de temps pour s\u2019adapter, et doit maintenir (voire surpasser) la performance de son pr\u00e9d\u00e9cesseur.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Assumer une possible perte de client\u00e8le<\/h3>\n\n\n\n<p>Il peut arriver qu&rsquo;une entreprise perde des clients suite \u00e0 un <strong>changement de direction<\/strong>. Dans l\u2019esprit des clients, cette situation peut d\u00e9couler d&rsquo;une baisse de la qualit\u00e9 des produits ou services par rapport \u00e0 l&rsquo;\u00e8re des anciens dirigeants. \u00c0 vous de leur prouver que la qualit\u00e9 restera la m\u00eame !<\/p>\n\n\n\n<p><em>A lire \u00e9galement : <a href=\"https:\/\/www.obat.fr\/blog\/aide-pole-emploi-creation-entreprise\/\" target=\"_blank\" rel=\"noreferrer noopener\">Aides P\u00f4le Emploi \u00e0 la cr\u00e9ation d\u2019entreprise : le guide<\/a><\/em><\/p>\n\n\n\n<h2 class=\"wp-block-heading\">O\u00f9 trouver une entreprise \u00e0 racheter ?<\/h2>\n\n\n\n<p>Trouver une <strong>entreprise \u00e0 vendre <\/strong>ou un <strong>commerce \u00e0 revendre<\/strong> peut \u00eatre complexe puisque ces structures annoncent rarement officiellement leur disponibilit\u00e9 pour une reprise. Parmi les principales m\u00e9thodes pour trouver une <strong>entreprise en cession<\/strong>, on retrouve :&nbsp;<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>le bouche-\u00e0-oreille, surtout dans les petites villes ;<\/li>\n\n\n\n<li>les sites sp\u00e9cialis\u00e9s, comme des plateformes listant les offres de cession d\u2019entreprise ;<\/li>\n\n\n\n<li>les sites g\u00e9r\u00e9s par des unions ou f\u00e9d\u00e9rations professionnelles ;<\/li>\n\n\n\n<li>les outils nationaux d&rsquo;annonce de cession (par exemple <a href=\"https:\/\/www.ffbatiment.fr\/gestion-entreprise\/creer-perenniser-mon-entreprise\/transmission-reprise-entreprise\/dossier-ba\/wwwtransmibatfr-tour-d-horizon-en-5-questions\">Transmibat<\/a> pour les entreprises du BTP par la F\u00e9d\u00e9ration Fran\u00e7aise du B\u00e2timent) ;<\/li>\n\n\n\n<li>les outils r\u00e9gionaux de cession d\u2019entreprise.<\/li>\n<\/ul>\n\n\n\n<h2 class=\"wp-block-heading\">Comment faire un rachat de soci\u00e9t\u00e9 ? Conseils et \u00e9tapes<\/h2>\n\n\n\n<h3 class=\"wp-block-heading\">1. Clarifiez votre projet de reprise d&rsquo;entreprise<\/h3>\n\n\n\n<p>Avant de commencer votre recherche, il est crucial de<strong> r\u00e9fl\u00e9chir \u00e0 vos motivations, objectifs, forces et faiblesses<\/strong>. Une fondation solide vous permettra de mener \u00e0 bien votre projet dans les meilleures conditions. Pour cela :&nbsp;<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>d\u00e9terminez le secteur et la taille de l&rsquo;entreprise que vous visez ;<\/li>\n\n\n\n<li>\u00e9valuez vos comp\u00e9tences pour la reprise et la gestion d&rsquo;une entreprise, sp\u00e9cifiquement dans le secteur choisi ;<\/li>\n\n\n\n<li>analysez vos ressources financi\u00e8res ;<\/li>\n\n\n\n<li>r\u00e9fl\u00e9chissez \u00e0 des aspects personnels comme votre disposition \u00e0 d\u00e9m\u00e9nager ou le temps que vous \u00eates pr\u00eat \u00e0 consacrer \u00e0 cette nouvelle activit\u00e9.<\/li>\n<\/ul>\n\n\n\n<h3 class=\"wp-block-heading\">2. Affinez votre recherche et s\u00e9lectionnez des entreprises<\/h3>\n\n\n\n<p>Deuxi\u00e8me \u00e9tape pour <strong>racheter une entreprise en cession<\/strong> : proc\u00e9der \u00e0 une s\u00e9lection minutieuse des entreprises potentielles. <\/p>\n\n\n\n<p>Contactez les Chambres de Commerce et d&rsquo;Industrie (CCI) dans vos r\u00e9gions cibl\u00e9es et rencontrez leurs \u00e9quipes sp\u00e9cialis\u00e9es en <strong>reprise-transmission<\/strong>. \u00c9cartez rapidement les offres qui ne correspondent pas \u00e0 vos crit\u00e8res (secteur d&rsquo;activit\u00e9, localisation, taille de l&rsquo;entreprise, etc.). <\/p>\n\n\n\n<p>Lorsque vous trouvez une entreprise int\u00e9ressante, pr\u00e9parez votre rencontre avec le dirigeant pour <strong>collecter un maximum d&rsquo;informations<\/strong> et laisser une impression positive. Mettez en avant vos atouts concurrentiels : comp\u00e9tences, exp\u00e9riences, qualit\u00e9 de votre apport financier, etc.<\/p>\n\n\n\n<p><em>A lire \u00e9galement : <a href=\"https:\/\/www.obat.fr\/blog\/conge-pour-creation-d-entreprise\/\" target=\"_blank\" rel=\"noreferrer noopener\">Cong\u00e9 pour cr\u00e9ation d\u2019entreprise : tout savoir pour se lancer<\/a><\/em><\/p>\n\n\n\n<h3 class=\"wp-block-heading\">3. \u00c9valuez la soci\u00e9t\u00e9 \u00e0 racheter<\/h3>\n\n\n\n<p>Avant de faire un <strong>rachat de soci\u00e9t\u00e9<\/strong>, il faut collecter toutes les informations n\u00e9cessaires pour d\u00e9finir le business plan, le montage juridique et financier. Commencez par analyser l&rsquo;activit\u00e9 et le march\u00e9 de l&rsquo;entreprise (ses clients et son environnement concurrentiel), puis \u00e9tudiez son organisation (ressources humaines, \u00e9quipements et savoir-faire). <\/p>\n\n\n\n<p>Enfin, passez en revue les aspects financiers comme le chiffre d&rsquo;affaires, la rentabilit\u00e9 et le niveau d&rsquo;endettement. Il se peut que le c\u00e9dant vous demande une<strong> lettre d&rsquo;intention<\/strong>, formalisant votre int\u00e9r\u00eat \u00e0 poursuivre l&rsquo;\u00e9tude du rachat et \u00e9tablissant un calendrier. Toute cette \u00e9tape d\u2019<strong>analyse de soci\u00e9t\u00e9<\/strong> vous permet \u00e9galement de<strong> juger du prix<\/strong> demand\u00e9 par le c\u00e9dant.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">4. \u00c9laborez votre business plan<\/h3>\n\n\n\n<p>Vous pouvez effectuer l&rsquo;achat directement ou via une holding, n\u00e9cessitant la cr\u00e9ation de cette structure. Le choix du <strong>statut juridique<\/strong> (<a href=\"https:\/\/www.obat.fr\/blog\/entreprise-individuelle\/\" target=\"_blank\" rel=\"noreferrer noopener\">Entreprise individuelle<\/a>, <a href=\"https:\/\/www.obat.fr\/blog\/statut-eurl\/\" target=\"_blank\" rel=\"noreferrer noopener\">EURL<\/a>, <a href=\"https:\/\/www.obat.fr\/blog\/sarl-definition\/\" target=\"_blank\" rel=\"noreferrer noopener\">SARL<\/a>, <a href=\"https:\/\/www.obat.fr\/blog\/statut-sas\/\" target=\"_blank\" rel=\"noreferrer noopener\">SAS<\/a>, <a href=\"https:\/\/www.obat.fr\/blog\/societe-anonyme\/\" target=\"_blank\" rel=\"noreferrer noopener\">SA<\/a>, SNC, etc.) aura des implications fiscales et sociales importantes. <\/p>\n\n\n\n<p>Vous devez aussi<strong> \u00e9laborer un business plan<\/strong> puisque ce document est crucial pour attester de la viabilit\u00e9 de votre projet de rachat et pour convaincre les financeurs. Votre business plan doit inclure :<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>votre profil (comp\u00e9tences, connaissance du secteur, apports financiers) ;<\/li>\n\n\n\n<li>votre projet (type de rachat, structure juridique envisag\u00e9e) ;<\/li>\n\n\n\n<li>une description d\u00e9taill\u00e9e de l&rsquo;entreprise (actifs, moyens d&rsquo;exploitation, personnel) ;<\/li>\n\n\n\n<li>l&rsquo;offre de produits ou services ;<\/li>\n\n\n\n<li>une analyse de march\u00e9 de la concurrence ;<\/li>\n\n\n\n<li>votre strat\u00e9gie de d\u00e9veloppement post-reprise ;<\/li>\n\n\n\n<li>la situation financi\u00e8re, pr\u00e9visions et montage financier du projet ;<\/li>\n\n\n\n<li>un calendrier des \u00e9tapes cl\u00e9s de la reprise.<\/li>\n<\/ul>\n\n\n\n<h3 class=\"wp-block-heading\">5. Concluez le rachat de la soci\u00e9t\u00e9<\/h3>\n\n\n\n<p>Il est maintenant temps de n\u00e9gocier la vente et de conclure la reprise ! Voici les diff\u00e9rentes \u00e9tapes :&nbsp;<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Le protocole d&rsquo;accord<\/strong> : ce document cl\u00e9 \u00e9tablit les conditions de la cession et engage les deux parties.&nbsp;<\/li>\n\n\n\n<li><strong>L\u2019audit<\/strong> : entre la signature du protocole et l\u2019acte de cession, il y a g\u00e9n\u00e9ralement un d\u00e9lai pour l\u2019audit de l\u2019entreprise, la consolidation des financements et la mise en place de la structure juridique ad\u00e9quate.<\/li>\n\n\n\n<li><strong>La structure<\/strong> : si vous rachetez via une holding, vous devez cr\u00e9er cette entit\u00e9. Malgr\u00e9 la simplification des formalit\u00e9s, quelques jours sont n\u00e9cessaires pour obtenir le Kbis, confirmant officiellement la soci\u00e9t\u00e9.<\/li>\n\n\n\n<li><strong>L&rsquo;acte de cession <\/strong>: le passage \u00e0 la signature de l&rsquo;acte de cession (devant un notaire, un avocat ou sous seing priv\u00e9) repr\u00e9sente l\u2019\u00e9tape finale. Apr\u00e8s la signature, des formalit\u00e9s administratives restent toutefois \u00e0 effectuer pour finaliser le rachat de soci\u00e9t\u00e9.<\/li>\n<\/ul>\n\n\n\n<h2 class=\"wp-block-heading\">Comment financer le rachat d\u2019une soci\u00e9t\u00e9 ?<\/h2>\n\n\n\n<h3 class=\"wp-block-heading\">M\u00e9thodes de financement<\/h3>\n\n\n\n<p>Pour financer un rachat de soci\u00e9t\u00e9, il existe plusieurs options disponibles :<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Fonds propres <\/strong>: il peut s\u2019agir d\u2019un apport personnel du repreneur (jusqu&rsquo;\u00e0 30 % du montant de la transaction), d\u2019une collecte de fonds aupr\u00e8s de proches ou de Business Angels (groupes d&rsquo;investisseurs et de repreneurs).<\/li>\n\n\n\n<li><strong>Aides financi\u00e8res <\/strong>: renseignez-vous sur votre \u00e9ligibilit\u00e9 aux aides de l&rsquo;\u00c9tat, comme l&rsquo;Arce ou l&rsquo;Accre, qui sont souvent cumulables avec des subventions r\u00e9gionales.<\/li>\n\n\n\n<li><strong>Pr\u00eats sur l\u2019honneur<\/strong> : ce sont des accords de financement sans int\u00e9r\u00eats, propos\u00e9s par des entit\u00e9s sp\u00e9cialis\u00e9es.<\/li>\n\n\n\n<li><strong>Cr\u00e9dit vendeur<\/strong> : il s\u2019agit d\u2019un emprunt souscrit par le repreneur \u00e0 rembourser ult\u00e9rieurement, permettant de couvrir une partie ou la totalit\u00e9 du co\u00fbt de la reprise.<\/li>\n\n\n\n<li><strong>Financements bancaires professionnels<\/strong> : contractez des pr\u00eats pouvant atteindre jusqu&rsquo;\u00e0 70 % du montant de l&rsquo;acquisition, avec un remboursement sur 5 \u00e0 7 ans.<\/li>\n<\/ul>\n\n\n\n<p><em>A lire \u00e9galement : <a href=\"https:\/\/www.obat.fr\/blog\/financer-creation-entreprise\/\" target=\"_blank\" rel=\"noreferrer noopener\">Comment financer son projet de cr\u00e9ation d\u2019entreprise ?<\/a><\/em><\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Reprise d\u2019entreprise sans apport : est-ce possible?<\/h3>\n\n\n\n<p>Il est assez courant dans le monde des affaires de r\u00e9aliser une <strong>reprise d\u2019entreprise sans apport personnel<\/strong>, notamment lorsque les entrepreneurs manquent de capital. Il arrive m\u00eame que certains entrepreneurs acqui\u00e8rent des entreprises en difficult\u00e9 pour un montant symbolique de 1 \u20ac.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Le cas de la reprise d&rsquo;entreprise dans le b\u00e2timent<\/h2>\n\n\n\n<p>Vous envisagez de <strong>lancer une soci\u00e9t\u00e9 dans le BTP <\/strong>? Plut\u00f4t de cr\u00e9er votre entreprise \u00e0 partir de z\u00e9ro, la reprise de soci\u00e9t\u00e9 peut \u00eatre une bonne option. Vous r\u00e9cup\u00e9rez ainsi une grande partie des actifs de l&rsquo;entreprise, mais aussi le portefeuille client existant.<\/p>\n\n\n\n<p>De plus, la gestion d&rsquo;une entreprise dans le b\u00e2timent va souvent de pair avec de nombreuses charges : mat\u00e9riels, \u00e9quipements, v\u00e9hicule utilitaire, locaux ou atelier, v\u00eatements de chantier, machines&#8230; Si vous optez pour un rachat, vous pourrez acqu\u00e9rir tous ces \u00e9l\u00e9ments <strong>\u00e0 un prix n\u00e9goci\u00e9 dans le co\u00fbt global<\/strong>. <\/p>\n\n\n\n<p>De plus, si l&rsquo;entreprise en question est d\u00e9j\u00e0 bien implant\u00e9e dans une zone g\u00e9ographique et b\u00e9n\u00e9ficie <strong>d&rsquo;une bonne r\u00e9putation<\/strong>, c&rsquo;est un immense coup de pouce pour se lancer ! En effet, le bouche \u00e0 oreilles est encore pr\u00e9dominant dans les m\u00e9tiers du b\u00e2timent lorsqu&rsquo;il s&rsquo;agit de trouver de nouveaux clients. <\/p>\n\n\n\n<p>Trouver<strong> une entreprise BTP en cession <\/strong>n&rsquo;est pas toujours simple : faites jouer votre r\u00e9seau et discutez avec les fournisseurs locaux qui peuvent avoir des informations de la part de leurs partenaires. Vous pouvez aussi regarder sur les <strong>sites d&rsquo;annonces acheteurs\/c\u00e9dants<\/strong> comme <a href=\"https:\/\/reprise-entreprise.bpifrance.fr\/entreprise-du-btp\" target=\"_blank\" rel=\"noreferrer noopener\">reprise-entreprise.bpifrance<\/a>, qui liste les offres d&rsquo;entreprises du b\u00e2timent disponibles pour un rachat.<\/p>\n\n\n\n<p><em>A lire \u00e9galement : <a href=\"https:\/\/www.obat.fr\/blog\/devenir-artisan-batiment\/\" target=\"_blank\" rel=\"noreferrer noopener\">Comment devenir artisan du b\u00e2timent ? Se lancer en 2026<\/a><\/em><\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<p>Le rachat de soci\u00e9t\u00e9 n\u2019est pas une op\u00e9ration sans risque, mais elle peut se r\u00e9v\u00e9ler tr\u00e8s int\u00e9ressante pour de nombreuses raisons. Racheter une entreprise vous permet de profiter des fondations solides mises en place par le c\u00e9dant, ce qui peut \u00eatre un gage de s\u00e9curit\u00e9 par rapport \u00e0 la cr\u00e9ation d\u2019entreprise. \u00c0 vous de bien analyser cette structure pour faire le bon choix !<\/p>\n\n\n<div class=\"kk-star-ratings kksr-auto kksr-align-left kksr-valign-bottom\"\n    data-payload='{&quot;align&quot;:&quot;left&quot;,&quot;id&quot;:&quot;6642&quot;,&quot;slug&quot;:&quot;default&quot;,&quot;valign&quot;:&quot;bottom&quot;,&quot;ignore&quot;:&quot;&quot;,&quot;reference&quot;:&quot;auto&quot;,&quot;class&quot;:&quot;&quot;,&quot;count&quot;:&quot;0&quot;,&quot;legendonly&quot;:&quot;&quot;,&quot;readonly&quot;:&quot;&quot;,&quot;score&quot;:&quot;0&quot;,&quot;starsonly&quot;:&quot;&quot;,&quot;best&quot;:&quot;5&quot;,&quot;gap&quot;:&quot;5&quot;,&quot;greet&quot;:&quot;Notez cet article&quot;,&quot;legend&quot;:&quot;0\\\/5 - (0 vote)&quot;,&quot;size&quot;:&quot;16&quot;,&quot;title&quot;:&quot;Rachat de soci\u00e9t\u00e9 : tout ce qu\\u0026#039;il faut savoir en [year]&quot;,&quot;width&quot;:&quot;0&quot;,&quot;_legend&quot;:&quot;{score}\\\/{best} - ({count} {votes})&quot;,&quot;font_factor&quot;:&quot;1.25&quot;}'>\n            \n<div class=\"kksr-stars\">\n    \n<div class=\"kksr-stars-inactive\">\n            <div class=\"kksr-star\" data-star=\"1\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 16px; height: 16px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" data-star=\"2\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 16px; height: 16px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" data-star=\"3\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 16px; height: 16px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" data-star=\"4\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 16px; height: 16px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" data-star=\"5\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 16px; height: 16px;\"><\/div>\n        <\/div>\n    <\/div>\n    \n<div class=\"kksr-stars-active\" style=\"width: 0px;\">\n            <div class=\"kksr-star\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 16px; height: 16px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 16px; height: 16px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 16px; height: 16px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 16px; height: 16px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 16px; height: 16px;\"><\/div>\n        <\/div>\n    <\/div>\n<\/div>\n                \n\n<div class=\"kksr-legend\" style=\"font-size: 12.8px;\">\n            <span class=\"kksr-muted\">Notez cet article<\/span>\n    <\/div>\n    <\/div>\n","protected":false},"excerpt":{"rendered":"<p>Le rachat de soci\u00e9t\u00e9 est tr\u00e8s int\u00e9ressant pour les personnes qui d\u00e9sirent se lancer dans l\u2019entrepreneuriat sans partir de z\u00e9ro. Vous pouvez ainsi acqu\u00e9rir une entreprise qui fonctionne d\u00e9j\u00e0, et notamment qui a fait ses preuves en termes de chiffres d\u2019affaires et de rentabilit\u00e9. Comment racheter une entreprise ? Quels sont les avantages et inconv\u00e9nients [&hellip;]<\/p>\n","protected":false},"author":11,"featured_media":6667,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[15],"tags":[],"class_list":["post-6642","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-creation-entreprise"],"acf":{"adam_posts_cta_bloc":{"adam_cb_image":null,"adam_cb_titre":"Trouvez des chantiers en sous traitance pr\u00e8s de chez vous.","adam_cb_cta":null},"hide_the_universal_cta":false},"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.5 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Rachat de soci\u00e9t\u00e9 : tout ce qu&#039;il faut savoir en 2026<\/title>\n<meta name=\"description\" content=\"Le rachat de soci\u00e9t\u00e9 peut \u00eatre un bon tremplin pour se lancer dans l\u2019entrepreneuriat partir de z\u00e9ro. D\u00e9couvrez tout ce qu&#039;il faut savoir !\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.obat.fr\/blog\/rachat-de-societe\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Rachat de soci\u00e9t\u00e9 : tout ce qu&#039;il faut savoir en 2026\" \/>\n<meta property=\"og:description\" content=\"Le rachat de soci\u00e9t\u00e9 peut \u00eatre un bon tremplin pour se lancer dans l\u2019entrepreneuriat partir de z\u00e9ro. D\u00e9couvrez tout ce qu&#039;il faut savoir !\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.obat.fr\/blog\/rachat-de-societe\/\" \/>\n<meta property=\"og:site_name\" content=\"Blog Obat\" \/>\n<meta property=\"article:published_time\" content=\"2023-12-04T17:20:10+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-01-10T14:04:50+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.obat.fr\/blog\/wp-content\/uploads\/2023\/11\/rachat-de-societe.png\" \/>\n\t<meta property=\"og:image:width\" content=\"735\" \/>\n\t<meta property=\"og:image:height\" content=\"360\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Mathilde Fauconnier\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Mathilde Fauconnier\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"10 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.obat.fr\\\/blog\\\/rachat-de-societe\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.obat.fr\\\/blog\\\/rachat-de-societe\\\/\"},\"author\":{\"name\":\"Mathilde Fauconnier\",\"@id\":\"https:\\\/\\\/www.obat.fr\\\/blog\\\/#\\\/schema\\\/person\\\/d6a74201e2ceca55da5c6e236380077e\"},\"headline\":\"Rachat de soci\u00e9t\u00e9 : tout ce qu&rsquo;il faut savoir en 2026\",\"datePublished\":\"2023-12-04T17:20:10+00:00\",\"dateModified\":\"2024-01-10T14:04:50+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.obat.fr\\\/blog\\\/rachat-de-societe\\\/\"},\"wordCount\":2061,\"image\":{\"@id\":\"https:\\\/\\\/www.obat.fr\\\/blog\\\/rachat-de-societe\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.obat.fr\\\/blog\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/rachat-de-societe.png\",\"articleSection\":[\"Cr\u00e9ation d'entreprise\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.obat.fr\\\/blog\\\/rachat-de-societe\\\/\",\"url\":\"https:\\\/\\\/www.obat.fr\\\/blog\\\/rachat-de-societe\\\/\",\"name\":\"Rachat de soci\u00e9t\u00e9 : tout ce qu'il faut savoir en 2026\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.obat.fr\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.obat.fr\\\/blog\\\/rachat-de-societe\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.obat.fr\\\/blog\\\/rachat-de-societe\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.obat.fr\\\/blog\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/rachat-de-societe.png\",\"datePublished\":\"2023-12-04T17:20:10+00:00\",\"dateModified\":\"2024-01-10T14:04:50+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.obat.fr\\\/blog\\\/#\\\/schema\\\/person\\\/d6a74201e2ceca55da5c6e236380077e\"},\"description\":\"Le rachat de soci\u00e9t\u00e9 peut \u00eatre un bon tremplin pour se lancer dans l\u2019entrepreneuriat partir de z\u00e9ro. D\u00e9couvrez tout ce qu'il faut savoir !\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.obat.fr\\\/blog\\\/wp-json\\\/wp\\\/v2\\\/posts\\\/6642#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.obat.fr\\\/blog\\\/rachat-de-societe\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.obat.fr\\\/blog\\\/rachat-de-societe\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.obat.fr\\\/blog\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/rachat-de-societe.png\",\"contentUrl\":\"https:\\\/\\\/www.obat.fr\\\/blog\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/rachat-de-societe.png\",\"width\":735,\"height\":360,\"caption\":\"rachat de soci\u00e9t\u00e9\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.obat.fr\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.obat.fr\\\/blog\\\/\",\"name\":\"Blog Obat\",\"description\":\"Blog Obat\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.obat.fr\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.obat.fr\\\/blog\\\/#\\\/schema\\\/person\\\/d6a74201e2ceca55da5c6e236380077e\",\"name\":\"Mathilde Fauconnier\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0a2f3a6912b4ed6e6822f1a7af825dd54683111e0146dafed3d083e913dd4b61?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0a2f3a6912b4ed6e6822f1a7af825dd54683111e0146dafed3d083e913dd4b61?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0a2f3a6912b4ed6e6822f1a7af825dd54683111e0146dafed3d083e913dd4b61?s=96&d=mm&r=g\",\"caption\":\"Mathilde Fauconnier\"},\"description\":\"R\u00e9dactrice web SEO, j\u2019accompagne Obat depuis 3 ans dans la cr\u00e9ation de contenus en d\u00e9cryptant les sp\u00e9cificit\u00e9s de la gestion du b\u00e2timent pour les artisans.\",\"sameAs\":[\"https:\\\/\\\/www.linkedin.com\\\/in\\\/mathilde-fauconnier-743180b3\\\/\"],\"url\":\"https:\\\/\\\/www.obat.fr\\\/blog\\\/author\\\/mathilde\\\/\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.obat.fr\\\/blog\\\/wp-json\\\/wp\\\/v2\\\/posts\\\/6642#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.obat.fr\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Blog\",\"item\":\"https:\\\/\\\/www.obat.fr\\\/blog\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Wp Json\",\"item\":\"https:\\\/\\\/www.obat.fr\\\/blog\\\/blog\\\/wp-json\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Wp\",\"item\":\"https:\\\/\\\/www.obat.fr\\\/blog\\\/blog\\\/wp-json\\\/wp\\\/\"},{\"@type\":\"ListItem\",\"position\":5,\"name\":\"V2\",\"item\":\"https:\\\/\\\/www.obat.fr\\\/blog\\\/blog\\\/wp-json\\\/wp\\\/v2\\\/\"},{\"@type\":\"ListItem\",\"position\":6,\"name\":\"Posts\",\"item\":\"https:\\\/\\\/www.obat.fr\\\/blog\\\/blog\\\/wp-json\\\/wp\\\/v2\\\/posts\\\/\"},{\"@type\":\"ListItem\",\"position\":7,\"name\":\"6642\",\"item\":\"https:\\\/\\\/www.obat.fr\\\/blog\\\/blog\\\/wp-json\\\/wp\\\/v2\\\/posts\\\/6642\\\/\"}]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Rachat de soci\u00e9t\u00e9 : tout ce qu'il faut savoir en 2026","description":"Le rachat de soci\u00e9t\u00e9 peut \u00eatre un bon tremplin pour se lancer dans l\u2019entrepreneuriat partir de z\u00e9ro. D\u00e9couvrez tout ce qu'il faut savoir !","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.obat.fr\/blog\/rachat-de-societe\/","og_locale":"fr_FR","og_type":"article","og_title":"Rachat de soci\u00e9t\u00e9 : tout ce qu'il faut savoir en 2026","og_description":"Le rachat de soci\u00e9t\u00e9 peut \u00eatre un bon tremplin pour se lancer dans l\u2019entrepreneuriat partir de z\u00e9ro. D\u00e9couvrez tout ce qu'il faut savoir !","og_url":"https:\/\/www.obat.fr\/blog\/rachat-de-societe\/","og_site_name":"Blog Obat","article_published_time":"2023-12-04T17:20:10+00:00","article_modified_time":"2024-01-10T14:04:50+00:00","og_image":[{"width":735,"height":360,"url":"https:\/\/www.obat.fr\/blog\/wp-content\/uploads\/2023\/11\/rachat-de-societe.png","type":"image\/png"}],"author":"Mathilde Fauconnier","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Mathilde Fauconnier","Dur\u00e9e de lecture estim\u00e9e":"10 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.obat.fr\/blog\/rachat-de-societe\/#article","isPartOf":{"@id":"https:\/\/www.obat.fr\/blog\/rachat-de-societe\/"},"author":{"name":"Mathilde Fauconnier","@id":"https:\/\/www.obat.fr\/blog\/#\/schema\/person\/d6a74201e2ceca55da5c6e236380077e"},"headline":"Rachat de soci\u00e9t\u00e9 : tout ce qu&rsquo;il faut savoir en 2026","datePublished":"2023-12-04T17:20:10+00:00","dateModified":"2024-01-10T14:04:50+00:00","mainEntityOfPage":{"@id":"https:\/\/www.obat.fr\/blog\/rachat-de-societe\/"},"wordCount":2061,"image":{"@id":"https:\/\/www.obat.fr\/blog\/rachat-de-societe\/#primaryimage"},"thumbnailUrl":"https:\/\/www.obat.fr\/blog\/wp-content\/uploads\/2023\/11\/rachat-de-societe.png","articleSection":["Cr\u00e9ation d'entreprise"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/www.obat.fr\/blog\/rachat-de-societe\/","url":"https:\/\/www.obat.fr\/blog\/rachat-de-societe\/","name":"Rachat de soci\u00e9t\u00e9 : tout ce qu'il faut savoir en 2026","isPartOf":{"@id":"https:\/\/www.obat.fr\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.obat.fr\/blog\/rachat-de-societe\/#primaryimage"},"image":{"@id":"https:\/\/www.obat.fr\/blog\/rachat-de-societe\/#primaryimage"},"thumbnailUrl":"https:\/\/www.obat.fr\/blog\/wp-content\/uploads\/2023\/11\/rachat-de-societe.png","datePublished":"2023-12-04T17:20:10+00:00","dateModified":"2024-01-10T14:04:50+00:00","author":{"@id":"https:\/\/www.obat.fr\/blog\/#\/schema\/person\/d6a74201e2ceca55da5c6e236380077e"},"description":"Le rachat de soci\u00e9t\u00e9 peut \u00eatre un bon tremplin pour se lancer dans l\u2019entrepreneuriat partir de z\u00e9ro. D\u00e9couvrez tout ce qu'il faut savoir !","breadcrumb":{"@id":"https:\/\/www.obat.fr\/blog\/wp-json\/wp\/v2\/posts\/6642#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.obat.fr\/blog\/rachat-de-societe\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.obat.fr\/blog\/rachat-de-societe\/#primaryimage","url":"https:\/\/www.obat.fr\/blog\/wp-content\/uploads\/2023\/11\/rachat-de-societe.png","contentUrl":"https:\/\/www.obat.fr\/blog\/wp-content\/uploads\/2023\/11\/rachat-de-societe.png","width":735,"height":360,"caption":"rachat de soci\u00e9t\u00e9"},{"@type":"WebSite","@id":"https:\/\/www.obat.fr\/blog\/#website","url":"https:\/\/www.obat.fr\/blog\/","name":"Blog Obat","description":"Blog Obat","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.obat.fr\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/www.obat.fr\/blog\/#\/schema\/person\/d6a74201e2ceca55da5c6e236380077e","name":"Mathilde Fauconnier","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/0a2f3a6912b4ed6e6822f1a7af825dd54683111e0146dafed3d083e913dd4b61?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/0a2f3a6912b4ed6e6822f1a7af825dd54683111e0146dafed3d083e913dd4b61?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/0a2f3a6912b4ed6e6822f1a7af825dd54683111e0146dafed3d083e913dd4b61?s=96&d=mm&r=g","caption":"Mathilde Fauconnier"},"description":"R\u00e9dactrice web SEO, j\u2019accompagne Obat depuis 3 ans dans la cr\u00e9ation de contenus en d\u00e9cryptant les sp\u00e9cificit\u00e9s de la gestion du b\u00e2timent pour les artisans.","sameAs":["https:\/\/www.linkedin.com\/in\/mathilde-fauconnier-743180b3\/"],"url":"https:\/\/www.obat.fr\/blog\/author\/mathilde\/"},{"@type":"BreadcrumbList","@id":"https:\/\/www.obat.fr\/blog\/wp-json\/wp\/v2\/posts\/6642#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.obat.fr\/blog\/"},{"@type":"ListItem","position":2,"name":"Blog","item":"https:\/\/www.obat.fr\/blog\/blog\/"},{"@type":"ListItem","position":3,"name":"Wp Json","item":"https:\/\/www.obat.fr\/blog\/blog\/wp-json\/"},{"@type":"ListItem","position":4,"name":"Wp","item":"https:\/\/www.obat.fr\/blog\/blog\/wp-json\/wp\/"},{"@type":"ListItem","position":5,"name":"V2","item":"https:\/\/www.obat.fr\/blog\/blog\/wp-json\/wp\/v2\/"},{"@type":"ListItem","position":6,"name":"Posts","item":"https:\/\/www.obat.fr\/blog\/blog\/wp-json\/wp\/v2\/posts\/"},{"@type":"ListItem","position":7,"name":"6642","item":"https:\/\/www.obat.fr\/blog\/blog\/wp-json\/wp\/v2\/posts\/6642\/"}]}]}},"_links":{"self":[{"href":"https:\/\/www.obat.fr\/blog\/wp-json\/wp\/v2\/posts\/6642","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.obat.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.obat.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.obat.fr\/blog\/wp-json\/wp\/v2\/users\/11"}],"replies":[{"embeddable":true,"href":"https:\/\/www.obat.fr\/blog\/wp-json\/wp\/v2\/comments?post=6642"}],"version-history":[{"count":0,"href":"https:\/\/www.obat.fr\/blog\/wp-json\/wp\/v2\/posts\/6642\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.obat.fr\/blog\/wp-json\/wp\/v2\/media\/6667"}],"wp:attachment":[{"href":"https:\/\/www.obat.fr\/blog\/wp-json\/wp\/v2\/media?parent=6642"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.obat.fr\/blog\/wp-json\/wp\/v2\/categories?post=6642"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.obat.fr\/blog\/wp-json\/wp\/v2\/tags?post=6642"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}