{"id":5318,"date":"2023-04-04T15:51:00","date_gmt":"2023-04-04T13:51:00","guid":{"rendered":"https:\/\/www.obat.fr\/blog\/?p=5318"},"modified":"2024-02-27T15:22:24","modified_gmt":"2024-02-27T14:22:24","slug":"charge-d-affaires-btp","status":"publish","type":"post","link":"https:\/\/www.obat.fr\/blog\/charge-d-affaires-btp\/","title":{"rendered":"Le charg\u00e9 d\u2019affaires dans le BTP | R\u00f4le, formation et salaire"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Un <strong>charg\u00e9 d&rsquo;affaires <\/strong>s&rsquo;occupe d\u2019accompagner ses clients dans les \u00e9tapes de mise en oeuvre d&rsquo;un projet de construction ou de r\u00e9novation. Il a pour mission <strong>de n\u00e9gocier<\/strong> et <strong>de<\/strong> <strong>choisir les prestataires<\/strong> ad\u00e9quats pour diminuer au maximum le co\u00fbt du chantier. Il poss\u00e8de donc un profil aussi <strong>technicien que commercial<\/strong>, avec un r\u00f4le hautement strat\u00e9gique \u00e0 forte valeur ajout\u00e9e pour son entreprise. <strong>Combien gagne un charg\u00e9 d\u2019affaires BTP<\/strong> ? Quelles formations suivre ? Quelles sont les comp\u00e9tences attendues ? Nous r\u00e9pondons \u00e0 ces questions dans cet article !<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Qu\u2019est-ce qu\u2019un charg\u00e9 d\u2019affaires dans le BTP ?<\/h2>\n\n\n\n<h3 class=\"wp-block-heading\">R\u00f4le et type de client<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Un <strong>charg\u00e9 d&rsquo;affaires dans le b\u00e2timent <\/strong>et les travaux publics supervise et suit l&rsquo;avancement de la construction d&rsquo;habitations, de locaux, de commerces, de ponts ou encore de routes. Il offre un accompagnement <strong>sur-mesure <\/strong>pour la r\u00e9alisation des travaux de ses clients. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Gr\u00e2ce \u00e0 son carnet d\u2019adresses et \u00e0 son<strong> portefeuille client <\/strong>bien fournis, il intervient sur des travaux de r\u00e9novation ou de construction. En tant que <strong>charg\u00e9 d\u2019affaires BTP<\/strong>, c\u2019est \u00e0 lui de choisir les fournisseurs et les sous-traitants (entreprises de ma\u00e7onnerie, de plomberie, d&rsquo;\u00e9lectricit\u00e9, etc.). <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Il d\u00e9finit alors <strong>un budget <\/strong>pour la r\u00e9alisation de l&rsquo;ouvrage, puis le fait valider par son client. Il \u00e9met des factures au fur et \u00e0 mesure de l&rsquo;avancement des travaux, s\u2019assure que le planning est respect\u00e9 et ma\u00eetrise les co\u00fbts. En r\u00e8gle g\u00e9n\u00e9rale, ses clients sont des grandes entreprises du b\u00e2timent, des locaux industriels ou des bureaux, mais aussi des entreprises de travaux publics.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em>A lire \u00e9galement : <a href=\"https:\/\/www.obat.fr\/blog\/suivi-de-chantier\/\" target=\"_blank\" rel=\"noreferrer noopener\" aria-label=\" (s\u2019ouvre dans un nouvel onglet)\">Suivi de chantier : comment le r\u00e9ussir ? 8 \u00e9tapes cl\u00e9s<\/a><\/em><\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Qualit\u00e9s et comp\u00e9tences attendues<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Un <strong>charg\u00e9 d\u2019affaires dans la construction<\/strong> est avant tout un commercial qui se doit d\u2019assurer des t\u00e2ches de prospection. Il doit donc combiner des <strong>comp\u00e9tences techniques<\/strong> avec des qualit\u00e9s <strong>sociales et professionnelles<\/strong> :&nbsp;<br><\/p>\n\n\n\n<figure class=\"wp-block-table is-style-stripes\"><table><tbody><tr><td><strong>Comp\u00e9tences techniques<\/strong><\/td><td><strong>Aptitudes professionnelles<\/strong><\/td><\/tr><tr><td>Culture \u00e9conomique<br>Culture juridique et r\u00e9glementaire concernant la passation des march\u00e9s en vigueur dans la construction<br>Connaissance des prestations ou des produits propos\u00e9s par l\u2019entreprise<br>Ma\u00eetrise des r\u00e8gles de n\u00e9gociation commerciale (vis-\u00e0-vis des clients comme des fournisseurs)<br>Ma\u00eetrise des outils de calcul de prix pour \u00e9tablir les propositions commerciales et n\u00e9gocier<br>Gestion administrative des affaires conclues (analyse des besoins client, signature des contrats, suivi commercial des travaux, etc.)<br>Ma\u00eetrise des outils informatiques<br>Connaissance d\u2019un outil CAO\/DAO et\/ou d\u2019un progiciel ERP<br>Connaissance des sp\u00e9cialit\u00e9s du BTP (urbanisme, architecture, \u00e9tudes, etc.)<br>Connaissance d\u2019une langue \u00e9trang\u00e8re si l\u2019entreprise est internationale<\/td><td>Sens de l\u2019\u00e9coute et de la communication<br>Capacit\u00e9s d\u2019adaptation<br>Bonne organisation<br>D\u00e9termination et t\u00e9nacit\u00e9<br>Polyvalence<br>Force de proposition<br>Force de conviction<br>Sens de la n\u00e9gociation<br>Aptitudes commerciales<br>Capacit\u00e9 \u00e0 travailler avec des \u00e9quipes pluridisciplinaires<\/td><\/tr><\/tbody><\/table><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">        <div class=\"endPostCta col-12 cta_bloc_generic\">\r\n            <div class=\"cta-column-left\">\r\n                <img decoding=\"async\" data-src=\"https:\/\/www.obat.fr\/blog\/wp-content\/uploads\/2026\/06\/Export-4-1.jpg\" alt=\"\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" class=\"lazyload\" style=\"--smush-placeholder-width: 1394px; --smush-placeholder-aspect-ratio: 1394\/876;\" \/>\r\n\r\n            <\/div>\r\n            <div class=\"cta-column-right\">\r\n                <div class=\"cta-title\">\r\n                    <div class=\"cta-title\">Obat est pr\u00eat pour la facturation \u00e9lectronique !<\/div>\r\n                <\/div>\r\n\r\n                \r\n                                    <a role=\"button\" class=\"obat-button medium-primary-white\" href=\"http:\/\/www.obat.fr\/click?campaign=1550\" target=\"_blank\">\r\n                        <span>D\u00e9marrer l\u2019essai gratuit<\/span>\r\n                        <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"12\" height=\"12\" viewBox=\"0 0 12 12\" fill=\"none\">\r\n                            <path d=\"M1 6L11 6M11 6L7.25 10M11 6L7.25 2\" stroke=\"currentColor\" stroke-width=\"1.5\" stroke-linecap=\"round\" stroke-linejoin=\"round\"><\/path>\r\n                        <\/svg>\r\n                    <\/a>\r\n                \r\n            <\/div>\r\n        <\/div>\r\n     <\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Les principales missions du charg\u00e9 d\u2019affaires<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Un charg\u00e9 d\u2019affaires BTP s&rsquo;assure <strong>du bon d\u00e9roulement d&rsquo;un chantier<\/strong>. Il fait en sorte que le planning et le budget soient respect\u00e9s. En mettant en \u0153uvre ses comp\u00e9tences commerciales, il aide \u00e0 <strong>r\u00e9duire le co\u00fbt des travaux<\/strong>. Voici ses principales missions :&nbsp;<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>d\u00e9finir les besoins des commanditaires de travaux ;<\/li>\n\n\n\n<li>diriger des missions de prospection aupr\u00e8s des bons prestataires ;<\/li>\n\n\n\n<li>n\u00e9gocier les contrats puis les r\u00e9diger ;<\/li>\n\n\n\n<li>servir d\u2019interlocuteur privil\u00e9gi\u00e9 entre le commanditaire d&rsquo;un chantier et les prestataires ext\u00e9rieurs (intervenants, sous-traitants, etc.) ;<\/li>\n\n\n\n<li>recommander les sous-traitants les plus fiables et les moins co\u00fbteux \u00e0 ses clients.<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\"><em>A lire \u00e9galement : <a href=\"https:\/\/www.obat.fr\/blog\/sous-traitance-batiment\/\" target=\"_blank\" rel=\"noreferrer noopener\" aria-label=\" (s\u2019ouvre dans un nouvel onglet)\">La sous-traitance dans le b\u00e2timent | Le guide pour tout comprendre<\/a><\/em><\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Quel est le salaire d\u2019un charg\u00e9 d\u2019affaires BTP ?<\/h2>\n\n\n\n<h3 class=\"wp-block-heading\">En tant que salari\u00e9<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Le <strong>salaire d\u2019un charg\u00e9 d\u2019affaires BTP<\/strong> est attractif, m\u00eame en d\u00e9but de carri\u00e8re. Pour un premier poste, un candidat peut en g\u00e9n\u00e9ral obtenir 2 500 \u20ac brut mensuels et franchir rapidement la barre des 4 000 \u20ac&nbsp;brut mensuels durant sa carri\u00e8re. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Le salaire moyen est de 3 100 \u20ac<\/strong> par mois tandis que le salaire maximal est de 7 800 \u20ac par mois. Il n\u2019existe toutefois aucune grille salariale pr\u00e9\u00e9tablie. Le m\u00e9tier de charg\u00e9 d&rsquo;affaires en b\u00e2timent<strong> <\/strong>peut \u00eatre r\u00e9mun\u00e9r\u00e9 par un <strong>salaire fixe<\/strong>, mais on lui associe souvent <strong>une part variable<\/strong> en fonction de l&rsquo;atteinte de ses objectifs. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Il est \u00e9galement possible d\u2019obtenir <strong>des avantages <\/strong>comme un v\u00e9hicule de fonction, la prise en charge des frais de d\u00e9placement ou encore des paniers-repas. Selon la taille de l&rsquo;entreprise, le charg\u00e9 d\u2019affaires peut aussi avoir des primes comme le <a href=\"https:\/\/www.journaldunet.fr\/management\/guide-du-management\/1201135-13eme-mois-calcul-salaire-imposable-tout-savoir\/\" target=\"_blank\" rel=\"noreferrer noopener\" aria-label=\" (s\u2019ouvre dans un nouvel onglet)\">13e mois<\/a>, une prime de participation ou une prime d&rsquo;int\u00e9ressement.&nbsp;<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">En ind\u00e9pendant<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Un <strong>charg\u00e9 d\u2019affaires auto-entrepreneur dans le BTP<\/strong> peut facturer ses clients \u00e0 la prestation ou \u00e0 l\u2019heure. C\u2019est \u00e0 vous de d\u00e9terminer le co\u00fbt de vos prestations selon votre secteur g\u00e9ographique, votre exp\u00e9rience, la demande et la qualit\u00e9 du portefeuille client et prestataire que vous pouvez mettre \u00e0 disposition de vos commanditaires.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em>A lire : <a href=\"https:\/\/www.obat.fr\/blog\/se-verser-un-salaire\/\" target=\"_blank\" rel=\"noreferrer noopener\" aria-label=\" (s\u2019ouvre dans un nouvel onglet)\">Comment se verser un salaire ? Auto-entrepreneur et chef d\u2019entreprise<\/a><\/em><\/p>\n\n\n\n<h3 class=\"wp-block-heading\">\u00c9volutions de carri\u00e8re&nbsp;<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Un <strong>charg\u00e9 d\u2019affaires en ma\u00eetres d\u2019\u0153uvre<\/strong> peut s\u2019occuper de chantiers de plus en plus complexes et grands pour gagner en exp\u00e9rience. Au fil du temps, il peut gagner en responsabilit\u00e9 pour devenir :&nbsp;<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>charg\u00e9 d&rsquo;affaires dans l&rsquo;industrie ;<\/li>\n\n\n\n<li>diagnostiqueur immobilier ;<\/li>\n\n\n\n<li>chef de projet travaux ;<\/li>\n\n\n\n<li>conducteur de travaux ;<\/li>\n\n\n\n<li>conducteur d\u2019op\u00e9rations ;<\/li>\n\n\n\n<li>directeur d&rsquo;agence ;<\/li>\n\n\n\n<li>ing\u00e9nieur d\u2019affaires.<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">Pour les profils les plus entreprenants, il est \u00e9galement possible de lancer sa propre entreprise du BTP en tant que <strong>charg\u00e9 d\u2019affaires ind\u00e9pendant<\/strong>. Vous pouvez coupler cette casquette avec celle d\u2019<strong>apporteur d\u2019affaires<\/strong> pour les entreprises.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em>A lire \u00e9galement : <a href=\"https:\/\/www.obat.fr\/blog\/apporteurs-affaires\/\" target=\"_blank\" rel=\"noreferrer noopener\" aria-label=\" (s\u2019ouvre dans un nouvel onglet)\">Les apporteurs d\u2019affaires BTP : Commissions et fonctionnement<\/a><\/em><\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Comment devenir charg\u00e9 d\u2019affaires BTP ? Formation<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Il existe plusieurs options de<strong> formation de charg\u00e9 d\u2019affaire BTP<\/strong>. Pour cela, il faut d\u00e9buter son cursus \u00e0 un niveau Bac+2 en validant :&nbsp;<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>un BTS B\u00e2timent&nbsp; ;<\/li>\n\n\n\n<li>un BTS NDRC (n\u00e9gociation et digitalisation de la relation client) ;<\/li>\n\n\n\n<li>un BTS MCO (management commercial op\u00e9rationnel).<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">Toutefois, il est conseill\u00e9 d\u2019aller jusqu\u2019\u00e0 un niveau Bac+5 puisque c\u2019est \u00e0 ce stade que se concentrent les recrutements. Pour atteindre ce niveau d\u2019\u00e9tudes, vous pouvez suivre et obtenir :&nbsp;<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>un dipl\u00f4me d&rsquo;\u00e9cole d&rsquo;ing\u00e9nieurs (sp\u00e9cialisation en BTP ou G\u00e9nie civil) ;<\/li>\n\n\n\n<li>un dipl\u00f4me d\u2019\u00e9cole sp\u00e9ciale des travaux publics ;<\/li>\n\n\n\n<li>un dipl\u00f4me d\u2019\u00e9cole des Ponts ParisTech ;<\/li>\n\n\n\n<li>un dipl\u00f4me de CESI \u00c9cole d\u2019ing\u00e9nieurs ;<\/li>\n\n\n\n<li>un master sp\u00e9cialis\u00e9 Management de projets de construction ;<\/li>\n\n\n\n<li>un master Management de projet.<\/li>\n<\/ul>\n\n\n\n<hr class=\"wp-block-separator has-css-opacity\"\/>\n\n\n\n<p class=\"wp-block-paragraph\">\u00c9tudes d\u2019un charg\u00e9 d\u2019affaire BTP, salaire moyen, qualit\u00e9s et comp\u00e9tences requises : vous savez \u00e0 pr\u00e9sent tout ce qu\u2019il faut savoir pour <strong>devenir charg\u00e9 d\u2019affaires dans le b\u00e2timent<\/strong> ! C\u2019est un m\u00e9tier qui r\u00e9mun\u00e8re bien et qui offre de multiples opportunit\u00e9s d\u2019\u00e9volution de carri\u00e8re pour les salari\u00e9s les plus motiv\u00e9s.<br><\/p>\n\n\n<div class=\"kk-star-ratings kksr-auto kksr-align-left kksr-valign-bottom\"\n    data-payload='{&quot;align&quot;:&quot;left&quot;,&quot;id&quot;:&quot;5318&quot;,&quot;slug&quot;:&quot;default&quot;,&quot;valign&quot;:&quot;bottom&quot;,&quot;ignore&quot;:&quot;&quot;,&quot;reference&quot;:&quot;auto&quot;,&quot;class&quot;:&quot;&quot;,&quot;count&quot;:&quot;0&quot;,&quot;legendonly&quot;:&quot;&quot;,&quot;readonly&quot;:&quot;&quot;,&quot;score&quot;:&quot;0&quot;,&quot;starsonly&quot;:&quot;&quot;,&quot;best&quot;:&quot;5&quot;,&quot;gap&quot;:&quot;5&quot;,&quot;greet&quot;:&quot;Notez cet article&quot;,&quot;legend&quot;:&quot;0\\\/5 - (0 vote)&quot;,&quot;size&quot;:&quot;16&quot;,&quot;title&quot;:&quot;Le charg\u00e9 d\u2019affaires dans le BTP | R\u00f4le, formation et salaire&quot;,&quot;width&quot;:&quot;0&quot;,&quot;_legend&quot;:&quot;{score}\\\/{best} - ({count} {votes})&quot;,&quot;font_factor&quot;:&quot;1.25&quot;}'>\n            \n<div class=\"kksr-stars\">\n    \n<div class=\"kksr-stars-inactive\">\n            <div class=\"kksr-star\" data-star=\"1\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 16px; height: 16px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" data-star=\"2\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 16px; height: 16px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" data-star=\"3\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 16px; height: 16px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" data-star=\"4\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 16px; height: 16px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" data-star=\"5\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 16px; height: 16px;\"><\/div>\n        <\/div>\n    <\/div>\n    \n<div class=\"kksr-stars-active\" style=\"width: 0px;\">\n            <div class=\"kksr-star\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 16px; height: 16px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 16px; height: 16px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 16px; height: 16px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 16px; height: 16px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 16px; height: 16px;\"><\/div>\n        <\/div>\n    <\/div>\n<\/div>\n                \n\n<div class=\"kksr-legend\" style=\"font-size: 12.8px;\">\n            <span class=\"kksr-muted\">Notez cet article<\/span>\n    <\/div>\n    <\/div>\n","protected":false},"excerpt":{"rendered":"<p>Un charg\u00e9 d&rsquo;affaires s&rsquo;occupe d\u2019accompagner ses clients dans les \u00e9tapes de mise en oeuvre d&rsquo;un projet de construction ou de r\u00e9novation. Il a pour mission de n\u00e9gocier et de choisir les prestataires ad\u00e9quats pour diminuer au maximum le co\u00fbt du chantier. Il poss\u00e8de donc un profil aussi technicien que commercial, avec un r\u00f4le hautement strat\u00e9gique [&hellip;]<\/p>\n","protected":false},"author":11,"featured_media":5321,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[7],"tags":[],"class_list":["post-5318","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-metiers-du-btp"],"acf":{"adam_posts_cta_bloc":{"adam_cb_image":null,"adam_cb_titre":"","adam_cb_description":"","adam_cb_cta":null},"hide_the_universal_cta":false},"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.6 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Le charg\u00e9 d\u2019affaires dans le BTP | R\u00f4le, formation et salaire<\/title>\n<meta name=\"description\" content=\"Combien gagne un charg\u00e9 d\u2019affaires BTP ? Quelles formations suivre ? Quelles sont les comp\u00e9tences attendues ? On r\u00e9ponds \u00e0 tout cela dans cet article !\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.obat.fr\/blog\/charge-d-affaires-btp\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Le charg\u00e9 d\u2019affaires dans le BTP | R\u00f4le, formation et salaire\" \/>\n<meta property=\"og:description\" content=\"Combien gagne un charg\u00e9 d\u2019affaires BTP ? Quelles formations suivre ? Quelles sont les comp\u00e9tences attendues ? On r\u00e9ponds \u00e0 tout cela dans cet article !\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.obat.fr\/blog\/charge-d-affaires-btp\/\" \/>\n<meta property=\"og:site_name\" content=\"Blog Obat\" \/>\n<meta property=\"article:published_time\" content=\"2023-04-04T13:51:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-02-27T14:22:24+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.obat.fr\/blog\/wp-content\/uploads\/2023\/03\/charge-d-affaires-btp.png\" \/>\n\t<meta property=\"og:image:width\" content=\"735\" \/>\n\t<meta property=\"og:image:height\" content=\"360\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Mathilde Fauconnier\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Mathilde Fauconnier\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.obat.fr\\\/blog\\\/charge-d-affaires-btp\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.obat.fr\\\/blog\\\/charge-d-affaires-btp\\\/\"},\"author\":{\"name\":\"Mathilde Fauconnier\",\"@id\":\"https:\\\/\\\/www.obat.fr\\\/blog\\\/#\\\/schema\\\/person\\\/d6a74201e2ceca55da5c6e236380077e\"},\"headline\":\"Le charg\u00e9 d\u2019affaires dans le BTP | R\u00f4le, formation et salaire\",\"datePublished\":\"2023-04-04T13:51:00+00:00\",\"dateModified\":\"2024-02-27T14:22:24+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.obat.fr\\\/blog\\\/charge-d-affaires-btp\\\/\"},\"wordCount\":1201,\"image\":{\"@id\":\"https:\\\/\\\/www.obat.fr\\\/blog\\\/charge-d-affaires-btp\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.obat.fr\\\/blog\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/charge-d-affaires-btp.png\",\"articleSection\":[\"Les m\u00e9tiers du BTP\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.obat.fr\\\/blog\\\/charge-d-affaires-btp\\\/\",\"url\":\"https:\\\/\\\/www.obat.fr\\\/blog\\\/charge-d-affaires-btp\\\/\",\"name\":\"Le charg\u00e9 d\u2019affaires dans le BTP | R\u00f4le, formation et salaire\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.obat.fr\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.obat.fr\\\/blog\\\/charge-d-affaires-btp\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.obat.fr\\\/blog\\\/charge-d-affaires-btp\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.obat.fr\\\/blog\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/charge-d-affaires-btp.png\",\"datePublished\":\"2023-04-04T13:51:00+00:00\",\"dateModified\":\"2024-02-27T14:22:24+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.obat.fr\\\/blog\\\/#\\\/schema\\\/person\\\/d6a74201e2ceca55da5c6e236380077e\"},\"description\":\"Combien gagne un charg\u00e9 d\u2019affaires BTP ? Quelles formations suivre ? Quelles sont les comp\u00e9tences attendues ? On r\u00e9ponds \u00e0 tout cela dans cet article !\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.obat.fr\\\/blog\\\/wp-json\\\/wp\\\/v2\\\/posts\\\/5318#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.obat.fr\\\/blog\\\/charge-d-affaires-btp\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.obat.fr\\\/blog\\\/charge-d-affaires-btp\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.obat.fr\\\/blog\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/charge-d-affaires-btp.png\",\"contentUrl\":\"https:\\\/\\\/www.obat.fr\\\/blog\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/charge-d-affaires-btp.png\",\"width\":735,\"height\":360,\"caption\":\"charg\u00e9 d'affaires BTP m\u00e9tier\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.obat.fr\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.obat.fr\\\/blog\\\/\",\"name\":\"Blog Obat\",\"description\":\"Blog Obat\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.obat.fr\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.obat.fr\\\/blog\\\/#\\\/schema\\\/person\\\/d6a74201e2ceca55da5c6e236380077e\",\"name\":\"Mathilde Fauconnier\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0a2f3a6912b4ed6e6822f1a7af825dd54683111e0146dafed3d083e913dd4b61?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0a2f3a6912b4ed6e6822f1a7af825dd54683111e0146dafed3d083e913dd4b61?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0a2f3a6912b4ed6e6822f1a7af825dd54683111e0146dafed3d083e913dd4b61?s=96&d=mm&r=g\",\"caption\":\"Mathilde Fauconnier\"},\"description\":\"R\u00e9dactrice web SEO, j\u2019accompagne Obat depuis 3 ans dans la cr\u00e9ation de contenus en d\u00e9cryptant les sp\u00e9cificit\u00e9s de la gestion du b\u00e2timent pour les artisans.\",\"sameAs\":[\"https:\\\/\\\/www.linkedin.com\\\/in\\\/mathilde-fauconnier-743180b3\\\/\"],\"url\":\"https:\\\/\\\/www.obat.fr\\\/blog\\\/author\\\/mathilde\\\/\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.obat.fr\\\/blog\\\/wp-json\\\/wp\\\/v2\\\/posts\\\/5318#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.obat.fr\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Blog\",\"item\":\"https:\\\/\\\/www.obat.fr\\\/blog\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Wp Json\",\"item\":\"https:\\\/\\\/www.obat.fr\\\/blog\\\/blog\\\/wp-json\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Wp\",\"item\":\"https:\\\/\\\/www.obat.fr\\\/blog\\\/blog\\\/wp-json\\\/wp\\\/\"},{\"@type\":\"ListItem\",\"position\":5,\"name\":\"V2\",\"item\":\"https:\\\/\\\/www.obat.fr\\\/blog\\\/blog\\\/wp-json\\\/wp\\\/v2\\\/\"},{\"@type\":\"ListItem\",\"position\":6,\"name\":\"Posts\",\"item\":\"https:\\\/\\\/www.obat.fr\\\/blog\\\/blog\\\/wp-json\\\/wp\\\/v2\\\/posts\\\/\"},{\"@type\":\"ListItem\",\"position\":7,\"name\":\"5318\",\"item\":\"https:\\\/\\\/www.obat.fr\\\/blog\\\/blog\\\/wp-json\\\/wp\\\/v2\\\/posts\\\/5318\\\/\"}]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Le charg\u00e9 d\u2019affaires dans le BTP | R\u00f4le, formation et salaire","description":"Combien gagne un charg\u00e9 d\u2019affaires BTP ? Quelles formations suivre ? Quelles sont les comp\u00e9tences attendues ? On r\u00e9ponds \u00e0 tout cela dans cet article !","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.obat.fr\/blog\/charge-d-affaires-btp\/","og_locale":"fr_FR","og_type":"article","og_title":"Le charg\u00e9 d\u2019affaires dans le BTP | R\u00f4le, formation et salaire","og_description":"Combien gagne un charg\u00e9 d\u2019affaires BTP ? Quelles formations suivre ? Quelles sont les comp\u00e9tences attendues ? On r\u00e9ponds \u00e0 tout cela dans cet article !","og_url":"https:\/\/www.obat.fr\/blog\/charge-d-affaires-btp\/","og_site_name":"Blog Obat","article_published_time":"2023-04-04T13:51:00+00:00","article_modified_time":"2024-02-27T14:22:24+00:00","og_image":[{"width":735,"height":360,"url":"https:\/\/www.obat.fr\/blog\/wp-content\/uploads\/2023\/03\/charge-d-affaires-btp.png","type":"image\/png"}],"author":"Mathilde Fauconnier","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Mathilde Fauconnier","Dur\u00e9e de lecture estim\u00e9e":"6 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.obat.fr\/blog\/charge-d-affaires-btp\/#article","isPartOf":{"@id":"https:\/\/www.obat.fr\/blog\/charge-d-affaires-btp\/"},"author":{"name":"Mathilde Fauconnier","@id":"https:\/\/www.obat.fr\/blog\/#\/schema\/person\/d6a74201e2ceca55da5c6e236380077e"},"headline":"Le charg\u00e9 d\u2019affaires dans le BTP | R\u00f4le, formation et salaire","datePublished":"2023-04-04T13:51:00+00:00","dateModified":"2024-02-27T14:22:24+00:00","mainEntityOfPage":{"@id":"https:\/\/www.obat.fr\/blog\/charge-d-affaires-btp\/"},"wordCount":1201,"image":{"@id":"https:\/\/www.obat.fr\/blog\/charge-d-affaires-btp\/#primaryimage"},"thumbnailUrl":"https:\/\/www.obat.fr\/blog\/wp-content\/uploads\/2023\/03\/charge-d-affaires-btp.png","articleSection":["Les m\u00e9tiers du BTP"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/www.obat.fr\/blog\/charge-d-affaires-btp\/","url":"https:\/\/www.obat.fr\/blog\/charge-d-affaires-btp\/","name":"Le charg\u00e9 d\u2019affaires dans le BTP | R\u00f4le, formation et salaire","isPartOf":{"@id":"https:\/\/www.obat.fr\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.obat.fr\/blog\/charge-d-affaires-btp\/#primaryimage"},"image":{"@id":"https:\/\/www.obat.fr\/blog\/charge-d-affaires-btp\/#primaryimage"},"thumbnailUrl":"https:\/\/www.obat.fr\/blog\/wp-content\/uploads\/2023\/03\/charge-d-affaires-btp.png","datePublished":"2023-04-04T13:51:00+00:00","dateModified":"2024-02-27T14:22:24+00:00","author":{"@id":"https:\/\/www.obat.fr\/blog\/#\/schema\/person\/d6a74201e2ceca55da5c6e236380077e"},"description":"Combien gagne un charg\u00e9 d\u2019affaires BTP ? Quelles formations suivre ? Quelles sont les comp\u00e9tences attendues ? On r\u00e9ponds \u00e0 tout cela dans cet article !","breadcrumb":{"@id":"https:\/\/www.obat.fr\/blog\/wp-json\/wp\/v2\/posts\/5318#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.obat.fr\/blog\/charge-d-affaires-btp\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.obat.fr\/blog\/charge-d-affaires-btp\/#primaryimage","url":"https:\/\/www.obat.fr\/blog\/wp-content\/uploads\/2023\/03\/charge-d-affaires-btp.png","contentUrl":"https:\/\/www.obat.fr\/blog\/wp-content\/uploads\/2023\/03\/charge-d-affaires-btp.png","width":735,"height":360,"caption":"charg\u00e9 d'affaires BTP m\u00e9tier"},{"@type":"WebSite","@id":"https:\/\/www.obat.fr\/blog\/#website","url":"https:\/\/www.obat.fr\/blog\/","name":"Blog Obat","description":"Blog Obat","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.obat.fr\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/www.obat.fr\/blog\/#\/schema\/person\/d6a74201e2ceca55da5c6e236380077e","name":"Mathilde Fauconnier","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/0a2f3a6912b4ed6e6822f1a7af825dd54683111e0146dafed3d083e913dd4b61?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/0a2f3a6912b4ed6e6822f1a7af825dd54683111e0146dafed3d083e913dd4b61?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/0a2f3a6912b4ed6e6822f1a7af825dd54683111e0146dafed3d083e913dd4b61?s=96&d=mm&r=g","caption":"Mathilde Fauconnier"},"description":"R\u00e9dactrice web SEO, j\u2019accompagne Obat depuis 3 ans dans la cr\u00e9ation de contenus en d\u00e9cryptant les sp\u00e9cificit\u00e9s de la gestion du b\u00e2timent pour les artisans.","sameAs":["https:\/\/www.linkedin.com\/in\/mathilde-fauconnier-743180b3\/"],"url":"https:\/\/www.obat.fr\/blog\/author\/mathilde\/"},{"@type":"BreadcrumbList","@id":"https:\/\/www.obat.fr\/blog\/wp-json\/wp\/v2\/posts\/5318#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.obat.fr\/blog\/"},{"@type":"ListItem","position":2,"name":"Blog","item":"https:\/\/www.obat.fr\/blog\/blog\/"},{"@type":"ListItem","position":3,"name":"Wp Json","item":"https:\/\/www.obat.fr\/blog\/blog\/wp-json\/"},{"@type":"ListItem","position":4,"name":"Wp","item":"https:\/\/www.obat.fr\/blog\/blog\/wp-json\/wp\/"},{"@type":"ListItem","position":5,"name":"V2","item":"https:\/\/www.obat.fr\/blog\/blog\/wp-json\/wp\/v2\/"},{"@type":"ListItem","position":6,"name":"Posts","item":"https:\/\/www.obat.fr\/blog\/blog\/wp-json\/wp\/v2\/posts\/"},{"@type":"ListItem","position":7,"name":"5318","item":"https:\/\/www.obat.fr\/blog\/blog\/wp-json\/wp\/v2\/posts\/5318\/"}]}]}},"_links":{"self":[{"href":"https:\/\/www.obat.fr\/blog\/wp-json\/wp\/v2\/posts\/5318","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.obat.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.obat.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.obat.fr\/blog\/wp-json\/wp\/v2\/users\/11"}],"replies":[{"embeddable":true,"href":"https:\/\/www.obat.fr\/blog\/wp-json\/wp\/v2\/comments?post=5318"}],"version-history":[{"count":0,"href":"https:\/\/www.obat.fr\/blog\/wp-json\/wp\/v2\/posts\/5318\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.obat.fr\/blog\/wp-json\/wp\/v2\/media\/5321"}],"wp:attachment":[{"href":"https:\/\/www.obat.fr\/blog\/wp-json\/wp\/v2\/media?parent=5318"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.obat.fr\/blog\/wp-json\/wp\/v2\/categories?post=5318"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.obat.fr\/blog\/wp-json\/wp\/v2\/tags?post=5318"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}